{"id":5102,"date":"2018-05-29T12:48:55","date_gmt":"2018-05-29T10:48:55","guid":{"rendered":"https:\/\/www.bcsoa.it\/\/?p=5102"},"modified":"2025-01-20T03:20:42","modified_gmt":"2025-01-20T02:20:42","slug":"creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana","status":"publish","type":"post","link":"https:\/\/www.bonfiglioliconsulting.com\/it\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\/","title":{"rendered":"Creiamo &#8220;L\u2018Intelligenza Artificiale al servizio dell\u2019intelligenza Umana&#8221;"},"content":{"rendered":"<p>I sistemi di Artificial Intelligence sono e saranno sempre di pi\u00f9 a supporto all\u2019attivit\u00e0 umana: attraverso tecniche di algoritmi di apprendimento automatico (<strong>Deep Machine Learning<\/strong>) impostati dall\u2019<strong>uomo<\/strong>, si \u00e8 in grado di trattare un\u2019enorme quantit\u00e0 di dati \u2013 milioni di immagini, per esempio \u2013 e riconoscere alcune caratteristiche discriminanti necessarie alla modellazione e risoluzione dei problemi, tra questi la Qualit\u00e0.<\/p>\n<p><strong>Bonfiglioli Consulting<\/strong> e <strong>Orobix<\/strong>, azienda\u00a0 specializzata in progettazione di sistemi di Intelligenza Artificiale, presenteranno alcuni <strong>esempi applicativi reali in ambito manifatturiero<\/strong> nei settori biomedicale, farmaceutico, presso-fusione, automotive e gomma.<\/p>\n<p>Sar\u00e0 possibile:<\/p>\n<ul>\n<li>Comprendere lo stato dell\u2019arte dell&#8217;applicazione degli algoritmi di AI al contesto manifatturiero<\/li>\n<li>Apprezzare come sia possibile oggettivare i difetti e segnalare in maniera preventiva e predittiva eventuali derive del processo<\/li>\n<li>Ottimizzare i processi e raggiungere la qualit\u00e0 a zero difetti<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Orobi<a href=\"https:\/\/orobix.com\/\"><img decoding=\"async\" class=\"alignleft size-full wp-image-5105 lazyload\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2018\/05\/logo-orobix.jpg\" alt=\"\" width=\"135\" height=\"80\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 135px; --smush-placeholder-aspect-ratio: 135\/80;\" \/><\/a>x sviluppa sistemi capaci di raccogliere dati e apprendere autonomamente la miglior strategia per la risoluzione di problemi concreti, provenienti da qualsiasi ambito di lavoro.<\/p>\n<p>In particolare, in ambito industriale, sviluppa sistemi di controllo qualit\u00e0 end of line, che apprendono autonomamente la forma e le caratteristiche dei pezzi ispezionati e rilevano anomalie o classificano difetti. Inoltre Orobix applica l\u2019apprendimento autonomo (reinforcement learning) all&#8217;ambito robotico, sviluppando sistemi che imparano automaticamente una strategia di comportamento che parte dalla rilevazione delle informazioni sul campo &#8211; tramite sensori o sistemi di visione &#8211; e procede per tentativi.<\/p>\n<p>La partecipazione \u00e8 gratuita. Per iscriversi compilare il form on-line\u00a0entro il 14 giugno 2018.<\/p>\n","protected":false},"excerpt":{"rendered":null,"protected":false},"author":73,"featured_media":5103,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"itsec_x_frame_options":"","footnotes":""},"categories":[20],"tags":[],"class_list":["post-5102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-eventi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2018IA al servizio dell\u2019intelligenza Umana<\/title>\n<meta name=\"description\" content=\"Creare intelligenza artificiale al servizio dell\u2019uomo: un progetto per migliorare produttivit\u00e0 e innovazione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2018IA al servizio dell\u2019intelligenza Umana\" \/>\n<meta property=\"og:description\" content=\"Creare intelligenza artificiale al servizio dell\u2019uomo: un progetto per migliorare produttivit\u00e0 e innovazione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonfiglioliconsulting.com\/it\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonfiglioli Consulting\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-29T10:48:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-20T02:20:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2018\/05\/robot-vs-uman.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"654\" \/>\n\t<meta property=\"og:image:height\" content=\"483\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Creiamo &#8220;L\u2018Intelligenza Artificiale al servizio dell\u2019intelligenza Umana&#8221;\",\"datePublished\":\"2018-05-29T10:48:55+00:00\",\"dateModified\":\"2025-01-20T02:20:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\\\/\"},\"wordCount\":252,\"image\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/robot-vs-uman.jpeg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\\\/\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\\\/\",\"name\":\"L\u2018IA al servizio dell\u2019intelligenza Umana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/robot-vs-uman.jpeg\",\"datePublished\":\"2018-05-29T10:48:55+00:00\",\"dateModified\":\"2025-01-20T02:20:42+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Creare intelligenza artificiale al servizio dell\u2019uomo: un progetto per migliorare produttivit\u00e0 e innovazione.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/robot-vs-uman.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/robot-vs-uman.jpeg\",\"width\":654,\"height\":483,\"caption\":\"Robot VS Uman \u2013 Bonfiglioli Consulting\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/\",\"name\":\"Bonfiglioli Consulting\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2018IA al servizio dell\u2019intelligenza Umana","description":"Creare intelligenza artificiale al servizio dell\u2019uomo: un progetto per migliorare produttivit\u00e0 e innovazione.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonfiglioliconsulting.com\/it\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2018IA al servizio dell\u2019intelligenza Umana","og_description":"Creare intelligenza artificiale al servizio dell\u2019uomo: un progetto per migliorare produttivit\u00e0 e innovazione.","og_url":"https:\/\/www.bonfiglioliconsulting.com\/it\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\/","og_site_name":"Bonfiglioli Consulting","article_published_time":"2018-05-29T10:48:55+00:00","article_modified_time":"2025-01-20T02:20:42+00:00","og_image":[{"width":654,"height":483,"url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2018\/05\/robot-vs-uman.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bonfiglioliconsulting.com\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\/#article","isPartOf":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\/"},"author":{"name":"","@id":""},"headline":"Creiamo &#8220;L\u2018Intelligenza Artificiale al servizio dell\u2019intelligenza Umana&#8221;","datePublished":"2018-05-29T10:48:55+00:00","dateModified":"2025-01-20T02:20:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\/"},"wordCount":252,"image":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2018\/05\/robot-vs-uman.jpeg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.bonfiglioliconsulting.com\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\/","url":"https:\/\/www.bonfiglioliconsulting.com\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\/","name":"L\u2018IA al servizio dell\u2019intelligenza Umana","isPartOf":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\/#primaryimage"},"image":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2018\/05\/robot-vs-uman.jpeg","datePublished":"2018-05-29T10:48:55+00:00","dateModified":"2025-01-20T02:20:42+00:00","author":{"@id":""},"description":"Creare intelligenza artificiale al servizio dell\u2019uomo: un progetto per migliorare produttivit\u00e0 e innovazione.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bonfiglioliconsulting.com\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.bonfiglioliconsulting.com\/creiamo-lintelligenza-artificiale-al-servizio-dellintelligenza-umana\/#primaryimage","url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2018\/05\/robot-vs-uman.jpeg","contentUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2018\/05\/robot-vs-uman.jpeg","width":654,"height":483,"caption":"Robot VS Uman \u2013 Bonfiglioli Consulting"},{"@type":"WebSite","@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website","url":"https:\/\/www.bonfiglioliconsulting.com\/it\/","name":"Bonfiglioli Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonfiglioliconsulting.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"","url":"https:\/\/www.bonfiglioliconsulting.com\/it\/author\/"}]}},"atf_populated":false,"_links":{"self":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/posts\/5102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/comments?post=5102"}],"version-history":[{"count":4,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/posts\/5102\/revisions"}],"predecessor-version":[{"id":5109,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/posts\/5102\/revisions\/5109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/media\/5103"}],"wp:attachment":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/media?parent=5102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/categories?post=5102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/tags?post=5102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}