{"id":27152,"date":"2021-09-20T13:15:01","date_gmt":"2021-09-20T11:15:01","guid":{"rendered":"https:\/\/www.bcsoa.it\/?p=27152"},"modified":"2025-01-20T03:24:47","modified_gmt":"2025-01-20T02:24:47","slug":"incontro-di-presentazione-del-libro-lean-digital-la-via-italiana-alla-fabbrica-5g","status":"publish","type":"post","link":"https:\/\/www.bonfiglioliconsulting.com\/it\/incontro-di-presentazione-del-libro-lean-digital-la-via-italiana-alla-fabbrica-5g\/","title":{"rendered":"Incontro di presentazione del libro Lean Digital &#8211; La via italiana alla fabbrica 5G"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/01\/banner-libro-lean-digital-1024x944.png\" alt=\"\" class=\"wp-image-26806 lazyload\" width=\"512\" height=\"472\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 512px; --smush-placeholder-aspect-ratio: 512\/472;\" \/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Mercoled\u00ec 29 settembre 2021<br>Ore 17.30-18.30<br>Confindustria Lecco e Sondrio<br>Sala conferenze Lecco, via Caprera 4<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Progettare la trasformazione 4,0 significa saper scegliere le tecnologie abilitanti funzionali alle aziende e poi innescarle a servizio del business e del valore per il cliente su processi snelli, robusti e flessibili. Il rischio, altrimenti, \u00e8 quello di digitalizzare anche gli sprechi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ma quali sono le tecnologie abilitanti funzionali alle aziende?<br>Come sceglierle?<br>Come il 5G trasforma la fabbrica?<br><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>INTRODUCE<\/strong><br><strong>Lorenzo Riva<\/strong> | Presidente di Confindustria Lecco e Sondrio<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>INTERVENGONO<\/strong><br><strong>Michele Bonfiglioli <\/strong>| Amministratore Delegato di Bonfiglioli Consulting e autore del libro<br><strong>Giuseppe Pace <\/strong>| Amministratore Delegato di Exor International, che ha implementato il primo laboratorio produttivo 5G in Italia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>MODERA<\/strong><br><strong>Cristina Pierini<\/strong> | Responsabile Area Competitivit\u00e0 e Mercati di Confindustria Lecco e Sondrio<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>INGRESSO SOLO CON GREEN PASS E PREVIA PRENOTAZIONE TRAMITE EMAIL: <a href=\"mailto:gandola@confindustrialeccoesondrio.it\">gandola@confindustrialeccoesondrio.it<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":null,"protected":false},"author":73,"featured_media":27153,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"itsec_x_frame_options":"","footnotes":""},"categories":[20,63],"tags":[106],"class_list":["post-27152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-eventi","category-rassegna-stampa","tag-ex-notizie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Libro Lean Digital \u2013 La via italiana alla fabbrica 5G<\/title>\n<meta name=\"description\" content=\"Presentazione del libro &quot;Lean Digital, la via italiana alla Fabbrica 5G&quot;: scopri nuove strategie di innovazione.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/incontro-di-presentazione-del-libro-lean-digital-la-via-italiana-alla-fabbrica-5g\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Libro Lean Digital \u2013 La via italiana alla fabbrica 5G\" \/>\n<meta property=\"og:description\" content=\"Presentazione del libro &quot;Lean Digital, la via italiana alla Fabbrica 5G&quot;: scopri nuove strategie di innovazione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonfiglioliconsulting.com\/it\/incontro-di-presentazione-del-libro-lean-digital-la-via-italiana-alla-fabbrica-5g\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonfiglioli Consulting\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-20T11:15:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-20T02:24:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/09\/Presentazione-libro-digital-lecco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2002\" \/>\n\t<meta property=\"og:image:height\" content=\"1127\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Incontro di presentazione del libro Lean Digital &#8211; La via italiana alla fabbrica 5G\",\"datePublished\":\"2021-09-20T11:15:01+00:00\",\"dateModified\":\"2025-01-20T02:24:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\\\/\"},\"wordCount\":147,\"image\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Presentazione-libro-digital-lecco.jpg\",\"keywords\":[\"ex-notizie\"],\"articleSection\":[\"Eventi\",\"Rassegna Stampa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\\\/\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\\\/\",\"name\":\"Libro Lean Digital \u2013 La via italiana alla fabbrica 5G\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Presentazione-libro-digital-lecco.jpg\",\"datePublished\":\"2021-09-20T11:15:01+00:00\",\"dateModified\":\"2025-01-20T02:24:47+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Presentazione del libro \\\"Lean Digital, la via italiana alla Fabbrica 5G\\\": scopri nuove strategie di innovazione.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Presentazione-libro-digital-lecco.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Presentazione-libro-digital-lecco.jpg\",\"width\":2002,\"height\":1127,\"caption\":\"Presentazione Libro Digital Lecco \u2013 Bonfiglioli Consulting\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/\",\"name\":\"Bonfiglioli Consulting\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Libro Lean Digital \u2013 La via italiana alla fabbrica 5G","description":"Presentazione del libro \"Lean Digital, la via italiana alla Fabbrica 5G\": scopri nuove strategie di innovazione.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonfiglioliconsulting.com\/it\/incontro-di-presentazione-del-libro-lean-digital-la-via-italiana-alla-fabbrica-5g\/","og_locale":"it_IT","og_type":"article","og_title":"Libro Lean Digital \u2013 La via italiana alla fabbrica 5G","og_description":"Presentazione del libro \"Lean Digital, la via italiana alla Fabbrica 5G\": scopri nuove strategie di innovazione.","og_url":"https:\/\/www.bonfiglioliconsulting.com\/it\/incontro-di-presentazione-del-libro-lean-digital-la-via-italiana-alla-fabbrica-5g\/","og_site_name":"Bonfiglioli Consulting","article_published_time":"2021-09-20T11:15:01+00:00","article_modified_time":"2025-01-20T02:24:47+00:00","og_image":[{"width":2002,"height":1127,"url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/09\/Presentazione-libro-digital-lecco.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bonfiglioliconsulting.com\/en\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\/#article","isPartOf":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/en\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\/"},"author":{"name":"","@id":""},"headline":"Incontro di presentazione del libro Lean Digital &#8211; La via italiana alla fabbrica 5G","datePublished":"2021-09-20T11:15:01+00:00","dateModified":"2025-01-20T02:24:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/en\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\/"},"wordCount":147,"image":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/en\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/09\/Presentazione-libro-digital-lecco.jpg","keywords":["ex-notizie"],"articleSection":["Eventi","Rassegna Stampa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.bonfiglioliconsulting.com\/en\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\/","url":"https:\/\/www.bonfiglioliconsulting.com\/en\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\/","name":"Libro Lean Digital \u2013 La via italiana alla fabbrica 5G","isPartOf":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/en\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\/#primaryimage"},"image":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/en\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/09\/Presentazione-libro-digital-lecco.jpg","datePublished":"2021-09-20T11:15:01+00:00","dateModified":"2025-01-20T02:24:47+00:00","author":{"@id":""},"description":"Presentazione del libro \"Lean Digital, la via italiana alla Fabbrica 5G\": scopri nuove strategie di innovazione.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bonfiglioliconsulting.com\/en\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.bonfiglioliconsulting.com\/en\/book-presentation-meeting-lean-digital-the-italian-way-to-the-5g-factory\/#primaryimage","url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/09\/Presentazione-libro-digital-lecco.jpg","contentUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/09\/Presentazione-libro-digital-lecco.jpg","width":2002,"height":1127,"caption":"Presentazione Libro Digital Lecco \u2013 Bonfiglioli Consulting"},{"@type":"WebSite","@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website","url":"https:\/\/www.bonfiglioliconsulting.com\/it\/","name":"Bonfiglioli Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonfiglioliconsulting.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"","url":"https:\/\/www.bonfiglioliconsulting.com\/it\/author\/"}]}},"atf_populated":false,"_links":{"self":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/posts\/27152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/comments?post=27152"}],"version-history":[{"count":7,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/posts\/27152\/revisions"}],"predecessor-version":[{"id":27164,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/posts\/27152\/revisions\/27164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/media\/27153"}],"wp:attachment":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/media?parent=27152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/categories?post=27152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/tags?post=27152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}