{"id":14069,"date":"2020-08-24T14:05:55","date_gmt":"2020-08-24T12:05:55","guid":{"rendered":"https:\/\/www.bcsoa.it\/\/?p=14069"},"modified":"2025-08-28T02:02:11","modified_gmt":"2025-08-28T00:02:11","slug":"digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective","status":"publish","type":"post","link":"https:\/\/www.bonfiglioliconsulting.com\/it\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\/","title":{"rendered":"Digital Roundtable&#8221;The challenges in the age of Digital Transformation from Silicon Valley perspective&#8221;"},"content":{"rendered":"<p>ALEXANDER FRED-OJALA and MARCUS ZETHRAEUS &nbsp;will be the Guests in this digital roundtable to share Silicon Valley perspective on:<\/p>\n<ul>\n<li>Data-Driven Business Model<\/li>\n<li>Blockchain<\/li>\n<li>Innovation Frameworks<\/li>\n<li>Exponential Growth<\/li>\n<\/ul>\n<p>During the live streaming, participants have the opportunity to interact with Q&amp;A sessions.<\/p>\n<p><strong>Chairman<\/strong><br \/>\n<a href=\"https:\/\/www.linkedin.com\/in\/michelebonfiglioli\">Michele Bonfiglioli<\/a>, CEO Bonfiglioli Consulting<\/p>\n<p><strong>Guests<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/www.linkedin.com\/in\/alexanderfo\/\">Alexander Fred-Ojala<\/a>&nbsp; is AI &amp; Blockchain Director, University of California, Berkeley and Co-founder and CEO of Predli Top-Tier Emerging Technology Advisory.<\/li>\n<li><a href=\"https:\/\/www.linkedin.com\/in\/marcuszethraeus\/\">Marcus Zethraeus<\/a>, <span class=\"background-details\">is Co-Founder of Predli, Top-Tier Emerging Technology Advisory offering world-class advise on emerging technology strategy, implementation, data driven business model Predli empowers Fortune 500 companies, SMEs, and startups to rapidly utilize the benefit of emerging technologies such as Blockchain, Artificial Intelligence and Innovation.<\/span><\/li>\n<\/ul>\n<p><em><strong>____<\/strong><\/em><\/p>\n<p><em><strong>SAVE THE DATE | 17th \u2013 18th November 2020<\/strong><\/em><br \/>\n<a href=\"https:\/\/www.leanfactoryschool.it\/la-scuola\/executive-program\/digital-innovation-x-two-day-master-class-for-executives-leaders\/\">Digital Innovation X \u2013 Two day Master Class for Executives &amp; Leaders&nbsp;<\/a>|&nbsp;This Master Class tackles the challenge of business creation and business transformation in the age of Digital Transformation. It is a comprehensive overview of everything you need to know in order to implement a successful digital strategy supporting leadership within your industry.<\/p>\n<p>____<\/p>\n<p><a href=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2020\/07\/GigiWang-2020-1.pdf\"><img decoding=\"async\" class=\"alignleft wp-image-14087 lazyload\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2020\/07\/IMG-GigiWang-360x332.png\" alt=\"\" width=\"200\" height=\"184\" data-srcset=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2020\/07\/IMG-GigiWang-360x332.png 360w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2020\/07\/IMG-GigiWang-750x692.png 750w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2020\/07\/IMG-GigiWang.png 837w\" data-sizes=\"(max-width: 200px) 100vw, 200px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 200px; --smush-placeholder-aspect-ratio: 200\/184;\" \/><\/a><a href=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2020\/07\/GigiWang-2020-1.pdf\">Leggi<\/a> l&#8217;intervista a Gigi Wang, Industry Fellow &amp; Faculty at UC&nbsp; Berkeley\u2019s Sutardja Center for&nbsp; Entrepreneurship.<\/p>\n","protected":false},"excerpt":{"rendered":null,"protected":false},"author":73,"featured_media":14936,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"itsec_x_frame_options":"","footnotes":""},"categories":[20,14],"tags":[],"class_list":["post-14069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-eventi","category-workshop"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Digital Talk: sfide del Silicon Valley | Bonfiglioli Consulting<\/title>\n<meta name=\"description\" content=\"Esplora le sfide della trasformazione digitale con una prospettiva unica direttamente dalla Silicon Valley.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digital Talk: sfide del Silicon Valley | Bonfiglioli Consulting\" \/>\n<meta property=\"og:description\" content=\"Esplora le sfide della trasformazione digitale con una prospettiva unica direttamente dalla Silicon Valley.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonfiglioliconsulting.com\/it\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonfiglioli Consulting\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-24T12:05:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-28T00:02:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2020\/08\/Digital-Roundtable.png\" \/>\n\t<meta property=\"og:image:width\" content=\"793\" \/>\n\t<meta property=\"og:image:height\" content=\"439\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Digital Roundtable&#8221;The challenges in the age of Digital Transformation from Silicon Valley perspective&#8221;\",\"datePublished\":\"2020-08-24T12:05:55+00:00\",\"dateModified\":\"2025-08-28T00:02:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\\\/\"},\"wordCount\":211,\"image\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Digital-Roundtable.png\",\"articleSection\":[\"Eventi\",\"Workshop &amp; Digital Talk\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\\\/\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\\\/\",\"name\":\"Digital Talk: sfide del Silicon Valley | Bonfiglioli Consulting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Digital-Roundtable.png\",\"datePublished\":\"2020-08-24T12:05:55+00:00\",\"dateModified\":\"2025-08-28T00:02:11+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Esplora le sfide della trasformazione digitale con una prospettiva unica direttamente dalla Silicon Valley.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/en\\\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Digital-Roundtable.png\",\"contentUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Digital-Roundtable.png\",\"width\":793,\"height\":439,\"caption\":\"Digital Roundtable \u2013 Bonfiglioli Consulting\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/\",\"name\":\"Bonfiglioli Consulting\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Digital Talk: sfide del Silicon Valley | Bonfiglioli Consulting","description":"Esplora le sfide della trasformazione digitale con una prospettiva unica direttamente dalla Silicon Valley.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonfiglioliconsulting.com\/it\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\/","og_locale":"it_IT","og_type":"article","og_title":"Digital Talk: sfide del Silicon Valley | Bonfiglioli Consulting","og_description":"Esplora le sfide della trasformazione digitale con una prospettiva unica direttamente dalla Silicon Valley.","og_url":"https:\/\/www.bonfiglioliconsulting.com\/it\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\/","og_site_name":"Bonfiglioli Consulting","article_published_time":"2020-08-24T12:05:55+00:00","article_modified_time":"2025-08-28T00:02:11+00:00","og_image":[{"width":793,"height":439,"url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2020\/08\/Digital-Roundtable.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bonfiglioliconsulting.com\/en\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\/#article","isPartOf":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/en\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\/"},"author":{"name":"","@id":""},"headline":"Digital Roundtable&#8221;The challenges in the age of Digital Transformation from Silicon Valley perspective&#8221;","datePublished":"2020-08-24T12:05:55+00:00","dateModified":"2025-08-28T00:02:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/en\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\/"},"wordCount":211,"image":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/en\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2020\/08\/Digital-Roundtable.png","articleSection":["Eventi","Workshop &amp; Digital Talk"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.bonfiglioliconsulting.com\/en\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\/","url":"https:\/\/www.bonfiglioliconsulting.com\/en\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\/","name":"Digital Talk: sfide del Silicon Valley | Bonfiglioli Consulting","isPartOf":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/en\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\/#primaryimage"},"image":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/en\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2020\/08\/Digital-Roundtable.png","datePublished":"2020-08-24T12:05:55+00:00","dateModified":"2025-08-28T00:02:11+00:00","author":{"@id":""},"description":"Esplora le sfide della trasformazione digitale con una prospettiva unica direttamente dalla Silicon Valley.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bonfiglioliconsulting.com\/en\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.bonfiglioliconsulting.com\/en\/digital-talk-the-challenges-in-the-age-of-digital-transformation-from-silicon-valley-perspective\/#primaryimage","url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2020\/08\/Digital-Roundtable.png","contentUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2020\/08\/Digital-Roundtable.png","width":793,"height":439,"caption":"Digital Roundtable \u2013 Bonfiglioli Consulting"},{"@type":"WebSite","@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website","url":"https:\/\/www.bonfiglioliconsulting.com\/it\/","name":"Bonfiglioli Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonfiglioliconsulting.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"","url":"https:\/\/www.bonfiglioliconsulting.com\/it\/author\/"}]}},"atf_populated":false,"_links":{"self":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/posts\/14069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/comments?post=14069"}],"version-history":[{"count":17,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/posts\/14069\/revisions"}],"predecessor-version":[{"id":25180,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/posts\/14069\/revisions\/25180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/media\/14936"}],"wp:attachment":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/media?parent=14069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/categories?post=14069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/tags?post=14069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}