{"id":87,"date":"2016-05-27T09:05:07","date_gmt":"2016-05-27T07:05:07","guid":{"rendered":"http:\/\/bcsoa-it.menabodigital.com\/?page_id=87"},"modified":"2023-03-03T11:54:05","modified_gmt":"2023-03-03T10:54:05","slug":"six-sigma","status":"publish","type":"page","link":"https:\/\/www.bonfiglioliconsulting.com\/it\/aree-intervento\/operational-excellence\/six-sigma\/","title":{"rendered":"Six Sigma e Lean Six Sigma"},"content":{"rendered":"<div id=\"saz-block-block_d78f7fab4c8c3f6fbd8cb81dcf7796e2\" class=\"d-none saz-block saz-block-acf-hero-servizi  bg-light bg-hero-servizi-eventi hero_overlay_parent vv lazyload\"\n     style=\"background:inherit; background-size:cover;\" data-bg=\"url(https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/02\/Bonfiglioli-PPT-CUBI-BIANCHI.png) center top no-repeat transparent\">\n    <div class=\"hero_overlay\"><\/div>\n    <div class=\"container hero_content\">\n        <div class=\"row align-items-end\">\n            <div class=\"col-12\">\n                 \n                    <div class=\"mt-3 mb-2 text-dark\"><div class=\"breadcrumbs\"><span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" title=\"Vai a Bonfiglioli Consulting.\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\" class=\"home\"><span property=\"name\">Home<\/span><\/a><meta property=\"position\" content=\"1\"><\/span><\/div><script type=\"application\/ld+json\">{\"@context\":\"http:\/\/schema.org\",\"@type\":\"BreadcrumbList\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@id\":\"https:\/\/www.bonfiglioliconsulting.com\/it\",\"name\":\"Bonfiglioli Consulting\"}}]}<\/script><\/div>\n                                \n                                    <h1 class=\"has-huge-font-size font-weight-bold mb-0 text-primary\">Lean Six Sigma<\/h1>\n                                                    <h2 class=\"has-medium-font-size my-3 font-weight-normal text-dark\">Le metodologie Lean Thinking e Six Sigma integrate insieme per gestire il miglioramento partendo dai dati, realizzato grazie alle persone<\/h2>\n                                <div class=\"mb-5 pb-4 pb-md-5\"><\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n    <svg class=\"onda-destra\" id=\"onda\" data-name=\"onda\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 180\"><path class=\"cls-1\" d=\"M0,180H1000V.4S458.72-.5,279.85.4c-49,.25-68.29,7.31-161.7,105.9C94.46,131.3,49.5,174.7,0,180Z\" transform=\"translate(0 0)\" style=\"fill: #ffffff\"\/><\/svg>\n<\/div>\n\n\n<section class=\"n_archive_hero lazyload\" style=\"background-image:inherit;\" data-bg-image=\"url(https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/02\/Bonfiglioli-PPT-CUBI-BIANCHI.png)\"> \n    <div class=\"container h-100 position-relative\">\n        <div class=\"d-flex items-center h-100\">\n            <div class=\"n_archive_hero_content align-self-end text-white\">\n                <div class=\"text-white\">\n                <div class=\"breadcrumbs\">\n                 \n                    <div class=\"mt-3 mb-2 text-dark\"><div class=\"breadcrumbs\"><span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" title=\"Vai a Bonfiglioli Consulting.\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\" class=\"home\"><span property=\"name\">Home<\/span><\/a><meta property=\"position\" content=\"1\"><\/span><\/div><script type=\"application\/ld+json\">{\"@context\":\"http:\/\/schema.org\",\"@type\":\"BreadcrumbList\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@id\":\"https:\/\/www.bonfiglioliconsulting.com\/it\",\"name\":\"Bonfiglioli Consulting\"}}]}<\/script><\/div>\n                                <\/div>\n                <\/div>\n                \n                \n                \n                                      <h1 class=\"text-white text-primary\">Lean Six Sigma<\/h1>\n                                \n                                    <div class=\"n_archive_desc\"> \n                     <p class=\"text-dark\">\n                       Le metodologie Lean Thinking e Six Sigma integrate insieme per gestire il miglioramento partendo dai dati, realizzato grazie alle persone                     <\/p>\n                    <\/div>  \n                                \n\n<\/div>\n        <\/div>\n    <\/div>\n    <div class=\"right_white_shape\">\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 180\">\n            <path class=\"cls-1\" d=\"M0,180H1000V.4S458.72-.5,279.85.4c-49,.25-68.29,7.31-161.7,105.9C94.46,131.3,49.5,174.7,0,180Z\" transform=\"translate(0 0)\"><\/path>\n        <\/svg>\n    <\/div>\n<\/section><div id=\"saz-block-id-G8UY52fF3ENW\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-YfXAoBbhVy80\" class=\"saz-block saz-block-core-spacer saz-block-height-60px\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-fb4VLz8nuEWm\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-FpQ6rSZuDOcm\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Il&nbsp;<strong>Lean Six Sigma<\/strong>&nbsp;\u00e8 un sistema di miglioramento continuo, focalizzato sull\u2019 esplorazione di modelli innovativi di gestione dei processi, realizzato cambiando i paradigmi degli standard consolidati e sfidando continuamente l\u2019azienda con il fine di raggiungere nuovi obiettivi.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-3QEyzlIlzad3\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-qDCpBbzj7ypk\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Il&nbsp;<strong>Lean Six Sigma<\/strong>&nbsp;coniuga l\u2019attenzione verso l\u2019eliminazione degli sprechi tipica del Lean Thinking con l\u2019approccio esplorativo basato sull\u2019interpretazione statistica dei dati caratteristica del Six Sigma.<br><\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-AXKUlzzacOOK\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-zIt2h8Rnx3sq\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Obiettivi raggiunti:<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-NJpN8LfiEhOb\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-hKy8TcB7oRC9\" class=\"saz-block saz-block-core-list\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<ul class=\"wp-block-list\"><div id=\"saz-block-id-oJugz2x3xeLo\" class=\"saz-block saz-block-core-list-item\">\n<li>Voice del Cliente (<strong>VoC<\/strong>), come driver per guidare i processi di miglioramento,<\/li>\n<\/div>\n\n<div id=\"saz-block-id-T0AeMJBS2RIk\" class=\"saz-block saz-block-core-list-item\">\n<li>Gestione del processo di miglioramento in maniera strutturata ed organizzata: non un evento occasionale, ma un cambio di mentalit\u00e0 aziendale che vede nei progetti di innovazione centro di profitto per l\u2019azienda,<\/li>\n<\/div>\n\n<div id=\"saz-block-id-P2oGieK20FIN\" class=\"saz-block saz-block-core-list-item\">\n<li>Lavoro di gruppo per condividere le competenze coordinati da una regia strategica.<\/li>\n<\/div><\/ul>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-ml3PxI9RsBqK\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-R7DHCqV48mV2\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Il Lean Six Sigma \u00e8 un metodo adatto a risolvere&nbsp;<strong>problemi complessi<\/strong>, in aziende che si vogliono mettere in gioco per crescere in competenze ed efficacia. \u00c8 applicabile in tutti i processi aziendali: manufacturing, transazionali, logistici, finanziari, di servizio e supporto grazie alla notevole quantit\u00e0 e qualit\u00e0 di strumenti a disposizione:<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-Aip7p3U81rm2\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-TKWakBW4A0pD\" class=\"saz-block saz-block-core-list\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<ul class=\"wp-block-list\"><div id=\"saz-block-id-sgwDMevZSJ3k\" class=\"saz-block saz-block-core-list-item\">\n<li>Strumenti Qualitativi: Mappatura dei processi, Value Stream Map, SIPOC, Ishikawa, Stratificazione, Data Collection Analysis, \u2026<\/li>\n<\/div>\n\n<div id=\"saz-block-id-BNwClLC1jE0V\" class=\"saz-block saz-block-core-list-item\">\n<li>Strumenti Quantitativi: Pareto, Analisi di Capability, Valutazione statistica dei processi, Test di Ipotesi, DoE, ANOVA, Conjoint Analysis, RSM, \u2026<\/li>\n<\/div><\/ul>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-IiDsoZd96qOZ\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-QJERXtk5Osda\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Il Lean Six Sigma sfrutta le informazioni fornite dai dati, inquadrandole nel proprio comportamento complessivo, usando l\u2019approccio statistico come forma mentale all\u2019analisi dei dati. Il messaggio fondamentale del pensiero statistico nel Lean Six Sigma \u00e8 legato al concetto di variabilit\u00e0 dei processi: dalla comprensione della variabilit\u00e0 dei processi nasce la necessit\u00e0 di non fidarsi del dato puntuale se non correttamente contestualizzato. La capacit\u00e0 di scelta dello strumento adatto in maniera economica (sforzo proporzionato all\u2019obiettivo) nasce con la frequentazione degli strumenti, con l\u2019esperienza nei progetti e con l\u2019utilizzo del metodo. Ragionare sui dati in termini complessivi e non solamente per il loro valore medio fornisce alle aziende un innegabile vantaggio.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-O1kuirRKWyAR\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-NObKrKVL1twf\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Per garantire efficacemente il processo di miglioramento, il Lean Six Sigma segue un approccio project-by-project. Ogni progetto \u00e8 un evento unico che deve dimostrare di portare vantaggi economici all\u2019azienda in termini di miglioramento dei KPI operativi e di conseguenti risultati economici e di essere organico con la vision strategica aziendale.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-suShRrzyZ4M9\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-o0pvO18Z55P4\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>La metodologia Lean Six Sigma \u00e8 sintetizzata nelle fasi di progetto secondo l\u2019acronimo <strong>DMAIC (Define &#8211; Measure &#8211; Analyse &#8211; Improve &#8211; Control<\/strong>). Grazie al metodo&nbsp;DMAIC, l\u2019azienda pu\u00f2 imparare a guidare i progetti secondo il metodo scientifico, concentrando gli sforzi sulla risoluzione dei problemi in maniera economica ed efficiente.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-RRAZQZY2cV8I\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div class=\"wp-block-image\"><div id=\"saz-block-id-35342\" class=\"saz-block saz-block-core-image saz-block-align-center saz-block-id-array saz-block-width-array saz-block-height-array saz-block-sizeslug-full saz-block-linkdestination-none\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2022\/08\/DMAIC.png\" alt=\"\" class=\"wp-image-35342 lazyload\" width=\"638\" height=\"423\" data-srcset=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2022\/08\/DMAIC.png 850w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2022\/08\/DMAIC-750x498.png 750w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2022\/08\/DMAIC-600x398.png 600w\" data-sizes=\"(max-width: 638px) 100vw, 638px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 638px; --smush-placeholder-aspect-ratio: 638\/423;\" \/><figcaption class=\"wp-element-caption\">Il metodo DMAIC<\/figcaption><\/figure>\n<\/div><\/div><\/div><\/div><\/div><div id=\"saz-block-id-Y8BY9xwQadEt\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-DzSC3u1q15hp\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>I 5 Step permettono di:<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-M0DgHIKz9fl8\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-U0Moeypzrio3\" class=\"saz-block saz-block-core-list saz-block-ordered-array saz-block-type-1\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<ol class=\"wp-block-list\" type=\"1\"><div id=\"saz-block-id-02VkPirlKGVe\" class=\"saz-block saz-block-core-list-item\">\n<li>Identificare in maniera chiara e condivisa i confini e le competenze del progetto;<\/li>\n<\/div>\n\n<div id=\"saz-block-id-cOM7ZGuUNYDn\" class=\"saz-block saz-block-core-list-item\">\n<li>Quantificare i miglioramenti operativi (DPMO, PPM) ed i conseguenti savings relativi;<\/li>\n<\/div>\n\n<div id=\"saz-block-id-8iRLhyq376Dv\" class=\"saz-block saz-block-core-list-item\">\n<li>Maturare progressivamente una conoscenza pi\u00f9 analitica del processo;<\/li>\n<\/div>\n\n<div id=\"saz-block-id-A8l8QdSJoebi\" class=\"saz-block saz-block-core-list-item\">\n<li>Consolidare le analisi dei dati orientate alla definizione degli elementi cruciali (Critical Few) per migliorare il processo;<\/li>\n<\/div>\n\n<div id=\"saz-block-id-S4tqVaTbJqCL\" class=\"saz-block saz-block-core-list-item\">\n<li>Identificare i possibili quick-win ed implementare tempestivamente le soluzioni efficaci;<\/li>\n<\/div>\n\n<div id=\"saz-block-id-6c582Bvvb4Ya\" class=\"saz-block saz-block-core-list-item\">\n<li>Controllare che i miglioramenti siano \u201cstrutturali\u201d, cio\u00e8 statisticamente significativi e non raggiunti per caso.<\/li>\n<\/div><\/ol>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-tufsaImvSOAi\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-NfNSKKMh7yiV\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p><strong>L\u2019organizzazione del miglioramento<\/strong><\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-twMnioOX3Dfj\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-fxIidDjCiDvB\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Uno degli indiscussi punti di forza della metodologia Lean Six Sigma \u00e8 la creazione di una struttura organizzativa \u201cmatriciale\u201d dedita alla ricerca del miglioramento. Questa struttura, attingendo alle risorse ad alto potenziale presenti in azienda, prevede di impegnarle per progetti di miglioramento, anche in aree tematicamente distanti dalla normale operativit\u00e0 giornaliera delle persone.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-wlL6cbzX2nJZ\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-ZS6OVeooK59y\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>L\u2019approccio crea degli esperti di un metodo, disseminandoli in tutte le funzioni, per condividere cultura e strumenti. Queste figure vengono identificate dal colore delle \u201ccinture\u201d, per indicare il livello di expertise raggiunto nella conoscenza e applicazione del metodo e degli strumenti: Lean White Belt, Lean Yellow Belt, LeanGreen Belt, Lean Black Belt, Master Black Belt.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-5ExerLegvgsz\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-ioV7X5wUJNz0\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Lo scopo non \u00e8 costruire degli specialisti di statistica, ma degli efficaci ottimizzatori di processo con mentalit\u00e0 Six Sigma. Spesso le funzionalit\u00e0 necessarie ad utilizzare in maniera approfondita i dati sono disponibili in un normale foglio di calcolo: \u00e8 la conoscenza dello strumento che permette di utilizzarlo in maniera corretta, efficace e funzionale allo scopo.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-E9IJyiJ7fBgt\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-Y7luGN1PF5io\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>La struttura:<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-YGGmRJdMCcLP\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-FFahJhrAH1Nq\" class=\"saz-block saz-block-core-list\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<ul class=\"wp-block-list\"><div id=\"saz-block-id-st1CWQQFMpnc\" class=\"saz-block saz-block-core-list-item\">\n<li><strong>Lean White Belt \u2013 <\/strong>introduzione al metodo, nessun coinvolgimento operativo nei progetti.<br>1 giornata di formazione;<\/li>\n<\/div>\n\n<div id=\"saz-block-id-se6n9J5gMvAJ\" class=\"saz-block saz-block-core-list-item\">\n<li><strong>Lean Yellow Belt \u2013 <\/strong>introduzione al metodo e agli strumenti rudimentali della statistica oltre che ai concetti di capability di processo, coinvolgimento parziale nei progetti normalmente come Process Expert;<\/li>\n<\/div>\n\n<div id=\"saz-block-id-Gfdi4cynaboI\" class=\"saz-block saz-block-core-list-item\">\n<li><strong>Lean Green Belt \u2013 <\/strong>conoscenza del metodoedei principalistrumenti di analisi qualitativa e quantitativa dei processi (strumenti di problem setting e problem solving); coinvolgimento strutturale nei progetti di miglioramento (impegno pari a circa il 10-20% del tempo complessivo), obiettivi di progetti e savings nell\u2019anno in funzione della dimensione aziendale;<\/li>\n<\/div>\n\n<div id=\"saz-block-id-sBigibnZCKuP\" class=\"saz-block saz-block-core-list-item\">\n<li><strong>Lean Black Belt<\/strong> \u2013 conoscenza approfondita del metodo, dei sistemi di Project Management, degli strumenti quantitativi e qualitativi e loro validazione.&nbsp; Coinvolgimento strutturale nel processo di miglioramento aziendale come Project Leader e coordinatore (circa 100% del tempo dedicato), forte commitment sugli obiettivi di saving annuali;<\/li>\n<\/div>\n\n<div id=\"saz-block-id-1yPon1zNDl0C\" class=\"saz-block saz-block-core-list-item\">\n<li><strong>Master Black Belt<\/strong> \u2013 conoscenza approfondita e specifica degli strumenti e delle metodologie di Project Management, figura di training e coaching oltre che di gestione di alto livello dell\u2019intero sistema Lean Six Sigma all\u2019interno dell\u2019azienda (impegno full time al miglioramento continuo), gestione e miglioramento degli obiettivi di saving annuale (deployment per obiettivi).<\/li>\n<\/div><\/ul>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-MumPdtfvg2k4\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-tCS0cq21yt0U\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>La <strong>Certificazione Lean Six Sigma <\/strong>infine garantisce un adeguato livello di conoscenza teorica, affiancato ad una efficace esperienza pratica. Per ottenere una Certificazione, infatti, \u00e8 necessario superare un test sulle conoscenze teoriche acquisite e portare a termine (almeno) un progetto. E\u2019 la Certificazione che permette di distinguere un project leader (Green Belt e Black Belt) da un semplice esperto in Statistica: i primi trovano un \u201cquindi\u201d operativo dalle analisi grazie alla forma mentis votata al problem solving, mentre i secondi si fermano ai numeri ed alle analisi formali.&nbsp;<\/p>\n<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":null,"protected":false},"author":141,"featured_media":20438,"parent":61,"menu_order":45,"comment_status":"closed","ping_status":"closed","template":"template-wide-blocchi.php","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"class_list":["post-87","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lean Six Sigma: Mentalit\u00e0 Sigma e Metodo DMAIC<\/title>\n<meta name=\"description\" content=\"Le metodologie Lean Thinking e Six Sigma integrate insieme per gestire il miglioramento partendo dai dati, grazie al metodo\u00a0DMAIC.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/aree-intervento\/operational-excellence\/six-sigma\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lean Six Sigma: Mentalit\u00e0 Sigma e Metodo DMAIC\" \/>\n<meta property=\"og:description\" content=\"Le metodologie Lean Thinking e Six Sigma integrate insieme per gestire il miglioramento partendo dai dati, grazie al metodo\u00a0DMAIC.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonfiglioliconsulting.com\/it\/aree-intervento\/operational-excellence\/six-sigma\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonfiglioli Consulting\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-03T10:54:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/02\/Master-Lean-Six-Sigma-2021.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/aree-intervento\\\/operational-excellence\\\/six-sigma\\\/\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/aree-intervento\\\/operational-excellence\\\/six-sigma\\\/\",\"name\":\"Lean Six Sigma: Mentalit\u00e0 Sigma e Metodo DMAIC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/aree-intervento\\\/operational-excellence\\\/six-sigma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/aree-intervento\\\/operational-excellence\\\/six-sigma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Master-Lean-Six-Sigma-2021.jpg\",\"datePublished\":\"2016-05-27T07:05:07+00:00\",\"dateModified\":\"2023-03-03T10:54:05+00:00\",\"description\":\"Le metodologie Lean Thinking e Six Sigma integrate insieme per gestire il miglioramento partendo dai dati, grazie al metodo\u00a0DMAIC.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/aree-intervento\\\/operational-excellence\\\/six-sigma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/aree-intervento\\\/operational-excellence\\\/six-sigma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Master-Lean-Six-Sigma-2021.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Master-Lean-Six-Sigma-2021.jpg\",\"width\":2000,\"height\":1125},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/\",\"name\":\"Bonfiglioli Consulting\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lean Six Sigma: Mentalit\u00e0 Sigma e Metodo DMAIC","description":"Le metodologie Lean Thinking e Six Sigma integrate insieme per gestire il miglioramento partendo dai dati, grazie al metodo\u00a0DMAIC.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonfiglioliconsulting.com\/it\/aree-intervento\/operational-excellence\/six-sigma\/","og_locale":"it_IT","og_type":"article","og_title":"Lean Six Sigma: Mentalit\u00e0 Sigma e Metodo DMAIC","og_description":"Le metodologie Lean Thinking e Six Sigma integrate insieme per gestire il miglioramento partendo dai dati, grazie al metodo\u00a0DMAIC.","og_url":"https:\/\/www.bonfiglioliconsulting.com\/it\/aree-intervento\/operational-excellence\/six-sigma\/","og_site_name":"Bonfiglioli Consulting","article_modified_time":"2023-03-03T10:54:05+00:00","og_image":[{"width":2000,"height":1125,"url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/02\/Master-Lean-Six-Sigma-2021.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bonfiglioliconsulting.com\/aree-intervento\/operational-excellence\/six-sigma\/","url":"https:\/\/www.bonfiglioliconsulting.com\/aree-intervento\/operational-excellence\/six-sigma\/","name":"Lean Six Sigma: Mentalit\u00e0 Sigma e Metodo DMAIC","isPartOf":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/aree-intervento\/operational-excellence\/six-sigma\/#primaryimage"},"image":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/aree-intervento\/operational-excellence\/six-sigma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/02\/Master-Lean-Six-Sigma-2021.jpg","datePublished":"2016-05-27T07:05:07+00:00","dateModified":"2023-03-03T10:54:05+00:00","description":"Le metodologie Lean Thinking e Six Sigma integrate insieme per gestire il miglioramento partendo dai dati, grazie al metodo\u00a0DMAIC.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bonfiglioliconsulting.com\/aree-intervento\/operational-excellence\/six-sigma\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.bonfiglioliconsulting.com\/aree-intervento\/operational-excellence\/six-sigma\/#primaryimage","url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/02\/Master-Lean-Six-Sigma-2021.jpg","contentUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/02\/Master-Lean-Six-Sigma-2021.jpg","width":2000,"height":1125},{"@type":"WebSite","@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website","url":"https:\/\/www.bonfiglioliconsulting.com\/it\/","name":"Bonfiglioli Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonfiglioliconsulting.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"atf_populated":false,"_links":{"self":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/pages\/87","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/users\/141"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/comments?post=87"}],"version-history":[{"count":21,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/pages\/87\/revisions"}],"predecessor-version":[{"id":41303,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/pages\/87\/revisions\/41303"}],"up":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/pages\/61"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/media\/20438"}],"wp:attachment":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/media?parent=87"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/tags?post=87"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}