{"id":74730,"date":"2026-07-17T10:34:00","date_gmt":"2026-07-17T08:34:00","guid":{"rendered":"https:\/\/www.bonfiglioliconsulting.com\/?page_id=74730"},"modified":"2026-07-17T12:50:42","modified_gmt":"2026-07-17T10:50:42","slug":"informativa-privacy-eventi-organizzati-in-collaborazione-con-partner","status":"publish","type":"page","link":"https:\/\/www.bonfiglioliconsulting.com\/it\/informativa-privacy-eventi-organizzati-in-collaborazione-con-partner\/","title":{"rendered":"Informativa Privacy \u2013 Eventi Organizzati in Collaborazione con Partner"},"content":{"rendered":"<div id=\"saz-block-block_3369ee9052c24ab70847550eeae75651\" class=\"d-none saz-block saz-block-acf-hero-servizi  bg-light bg-hero-servizi-eventi hero_overlay_parent vv\"\n     style=\"background-color:#32468C;\">\n    <div class=\"hero_overlay\"><\/div>\n    <div class=\"container hero_content\">\n        <div class=\"row align-items-end\">\n            <div class=\"col-12\">\n                 \n                    <div class=\"mt-3 mb-2 text-white\"><div class=\"breadcrumbs\"><span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" title=\"Vai a Bonfiglioli Consulting.\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\" class=\"home\"><span property=\"name\">Home<\/span><\/a><meta property=\"position\" content=\"1\"><\/span><\/div><script type=\"application\/ld+json\">{\"@context\":\"http:\/\/schema.org\",\"@type\":\"BreadcrumbList\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@id\":\"https:\/\/www.bonfiglioliconsulting.com\/it\",\"name\":\"Bonfiglioli Consulting\"}}]}<\/script><\/div>\n                                \n                                    <h1 class=\"has-huge-font-size font-weight-bold mb-0 text-white\">Informativa Privacy \u2013 Eventi Organizzati in Collaborazione con Partner<\/h1>\n                                                <div class=\"mb-5 pb-4 pb-md-5\"><\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n    <svg class=\"onda-destra\" id=\"onda\" data-name=\"onda\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 180\"><path class=\"cls-1\" d=\"M0,180H1000V.4S458.72-.5,279.85.4c-49,.25-68.29,7.31-161.7,105.9C94.46,131.3,49.5,174.7,0,180Z\" transform=\"translate(0 0)\" style=\"fill: #ffffff\"\/><\/svg>\n<\/div>\n\n\n<section class=\"n_archive_hero\" style=\"\"> \n    <div class=\"container h-100 position-relative\">\n        <div class=\"d-flex items-center h-100\">\n            <div class=\"n_archive_hero_content align-self-end text-white\">\n                <div class=\"text-white\">\n                <div class=\"breadcrumbs\">\n                 \n                    <div class=\"mt-3 mb-2 text-white\"><div class=\"breadcrumbs\"><span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" title=\"Vai a Bonfiglioli Consulting.\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\" class=\"home\"><span property=\"name\">Home<\/span><\/a><meta property=\"position\" content=\"1\"><\/span><\/div><script type=\"application\/ld+json\">{\"@context\":\"http:\/\/schema.org\",\"@type\":\"BreadcrumbList\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@id\":\"https:\/\/www.bonfiglioliconsulting.com\/it\",\"name\":\"Bonfiglioli Consulting\"}}]}<\/script><\/div>\n                                <\/div>\n                <\/div>\n                \n                \n                \n                                      <h1 class=\"text-white text-white\">Informativa Privacy \u2013 Eventi Organizzati in Collaborazione con Partner<\/h1>\n                                \n                                \n\n<\/div>\n        <\/div>\n    <\/div>\n    <div class=\"right_white_shape\">\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 180\">\n            <path class=\"cls-1\" d=\"M0,180H1000V.4S458.72-.5,279.85.4c-49,.25-68.29,7.31-161.7,105.9C94.46,131.3,49.5,174.7,0,180Z\" transform=\"translate(0 0)\"><\/path>\n        <\/svg>\n    <\/div>\n<\/section><div id=\"saz-block-id-4GVNYVsFz9lG\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-qvooC9Q76Kzh\" class=\"saz-block saz-block-core-spacer saz-block-height-50px\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-dmEApuXR1ufD\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-YHBSQtaY0xNY\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p class=\"wp-block-paragraph\">Ai sensi dell\u2019art. 13 del Regolamento 2016\/679\/UE (di seguito \u201cRegolamento\u201d) Bonfiglioli Consulting S.r.l., con sede in Via Isonzo 61, 40033 Casalecchio di Reno (BO), C.F. e P.IVA 02646871208 nella sua qualit\u00e0 di Titolare del Trattamento, la informa che i suoi dati personali saranno trattati per:<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-p6xvsE5yO0Sq\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-53ZopDTQaNut\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p class=\"wp-block-paragraph\">a) consentire al Titolare di gestire l\u2019organizzazione degli eventi (workshop, percorsi di formazione) per i quali i dati sono raccolti;<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-ZFBg9UANMFeY\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-iZRUnPLiW7PY\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p class=\"wp-block-paragraph\">b) consentire al Titolare l\u2019invio tramite mail, posta e\/o contatti telefonici, di newsletter, comunicazioni commerciali e\/o materiale informativo sui prodotti e i servizi offerti;<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-6te8koLk96hR\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-YurYVhJxage4\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p class=\"wp-block-paragraph\">c) consentire al Titolare l\u2019utilizzo delle immagini, del nome e della voce attraverso riprese fotografiche e\/o audiovisive per finalit\u00e0 di carattere didattico, promozionale, sia mediante i canali predisposti per&nbsp;questo uso sia attraverso il sito internet o social network.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-fmXRxz2QaF5A\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-khn6r4EctALi\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p class=\"wp-block-paragraph\">d) consentire al Titolare la comunicazione dei dati personali dell&#8217;interessato relativi all&#8217;iscrizione (a titolo esemplificativo e non esaustivo: nome, cognome, azienda, ruolo, email, telefono e ogni altro dato fornito in fase di registrazione) esclusivamente al partner specifico con il quale il Titolare organizza in collaborazione l&#8217;iniziativa, il progetto o l&#8217;evento per il quale l&#8217;interessato si iscrive, per finalit\u00e0 connesse alla realizzazione di tale iniziativa, progetto o evento svolto in partnership.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-Nwe5YQlh8vi5\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-9DBtBtOkjELJ\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p class=\"wp-block-paragraph\">La base giuridica \u00e8 il legittimo interesse per le finalit\u00e0 di cui al punto a).<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-qA70cYXIQUaX\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-tY6NAJHVcFiK\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p class=\"wp-block-paragraph\">La base giuridica \u00e8 il consenso liberamente prestato dall\u2019interessato per le finalit\u00e0 di cui ai punti b),  c) e d): l\u2019eventuale rifiuto, integrale o parziale, di conferire i dati o il conferimento inesatto o non veritiero degli stessi determiner\u00e0 l\u2019impossibilit\u00e0 di trattare i dati.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-y83yKUfKT9AS\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-wtyDH6NeQk2k\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p class=\"wp-block-paragraph\">Il trattamento potr\u00e0 riguardare tutte le operazioni indicate dall\u2019art. 4 n. 2 del \u201cRegolamento\u201d.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-NMFBJVXVAguX\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-w5UfxJKJEB7w\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p class=\"wp-block-paragraph\">In ogni caso saranno rispettati i principi e i limiti di correttezza, liceit\u00e0, finalit\u00e0, qualit\u00e0, pertinenza, non eccedenza e trasparenza.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-ZdM3C87pDAAN\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-75pBk9XkgJ7C\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p class=\"wp-block-paragraph\">I dati personali saranno trattati direttamente dall\u2019organizzazione del Titolare con strumenti automatizzati per il tempo strettamente necessario per le finalit\u00e0 di cui ai punti a), b), c) e d) della presente informativa e verranno conservati in archivi elettronici e\/o cartacei per un periodo di 5 anni.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-zhnoAcSLtToQ\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-v1O8jya2aTbM\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p class=\"wp-block-paragraph\">I dati non verranno comunicati a terzi, salvo i casi di cui ai punti c) e d), per la cui attivit\u00e0 il trattamento verr\u00e0 svolto con logiche strettamente correlate alle finalit\u00e0 indicate e con modalit\u00e0 che garantiscano la riservatezza.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-uyU2dDLEiBIz\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-IfEe66rBHG3A\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p class=\"wp-block-paragraph\">L\u2019interessato ha diritto di:<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-igKUteyT8aCv\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-5dwU180qrin7\" class=\"saz-block saz-block-core-list\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<ul class=\"wp-block-list\"><div id=\"saz-block-id-ZNI8ORaSQCC5\" class=\"saz-block saz-block-core-list-item\">\n<li>chiedere al Titolare l\u2019accesso ai dati personali, la rettifica o la cancellazione degli stessi o la limitazione del trattamento;<\/li>\n<\/div>\n\n<div id=\"saz-block-id-teX74svh9IL1\" class=\"saz-block saz-block-core-list-item\">\n<li>opporsi al loro trattamento;<\/li>\n<\/div>\n\n<div id=\"saz-block-id-ZQp1SK86pl6F\" class=\"saz-block saz-block-core-list-item\">\n<li>chiedere al Titolare la portabilit\u00e0 dei dati;<\/li>\n<\/div>\n\n<div id=\"saz-block-id-lzgLxP98Nhdl\" class=\"saz-block saz-block-core-list-item\">\n<li>revocare il consenso in qualsiasi momento senza pregiudicare la liceit\u00e0 del trattamento basata sul consenso prestato in precedenza;<\/li>\n<\/div>\n\n<div id=\"saz-block-id-4pUTe9IWKWOY\" class=\"saz-block saz-block-core-list-item\">\n<li>proporre reclamo ad un\u2019autorit\u00e0 di controllo;<\/li>\n<\/div>\n\n<div id=\"saz-block-id-5zF727dfd3ah\" class=\"saz-block saz-block-core-list-item\">\n<li>conoscere l\u2019esistenza di un processo decisionale automatizzato, le informazioni sulla logica utilizzata e le conseguenze previste in caso di trattamento.<\/li>\n<\/div><\/ul>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-w1CJIoqBmhys\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-WaoXreL3LdGp\" class=\"saz-block saz-block-core-buttons saz-block-fontsize-medium saz-block-layout-array\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<div class=\"wp-block-buttons has-custom-font-size has-medium-font-size is-vertical is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-569b4b61 wp-block-buttons-is-layout-flex\"><div id=\"saz-block-id-fsZ4ruWcCB2o\" class=\"saz-block saz-block-core-button saz-block-width-array saz-block-classname-pc-btn saz-block-style-array\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100 pc-btn\"><a class=\"wp-block-button__link has-text-align-center wp-element-button\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/privacy-policy-completa\/\">LEGGI PRIVACY POLICY COMPLETA<\/a><\/div>\n<\/div><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":null,"protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":999,"comment_status":"closed","ping_status":"closed","template":"template-wide-blocchi.php","meta":{"_acf_changed":false,"itsec_x_frame_options":"","footnotes":""},"tags":[],"class_list":["post-74730","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Informativa sulla Privacy - Bonfiglioli Consulting<\/title>\n<meta name=\"description\" content=\"Consulta l&#039;informativa sulla privacy del sito Bonfiglioli Consulting, ai sensi dell\u2019art. 13 del D. Lgs 196\/2003 e dell\u2019art. 13 del Regolamento 2016\/679\/UE.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/informativa-privacy-eventi-organizzati-in-collaborazione-con-partner\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informativa sulla Privacy - Bonfiglioli Consulting\" \/>\n<meta property=\"og:description\" content=\"Consulta l&#039;informativa sulla privacy del sito Bonfiglioli Consulting, ai sensi dell\u2019art. 13 del D. Lgs 196\/2003 e dell\u2019art. 13 del Regolamento 2016\/679\/UE.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonfiglioliconsulting.com\/it\/informativa-privacy-eventi-organizzati-in-collaborazione-con-partner\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonfiglioli Consulting\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-17T10:50:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/informativa-privacy-eventi-organizzati-in-collaborazione-con-partner\\\/\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/informativa-privacy-eventi-organizzati-in-collaborazione-con-partner\\\/\",\"name\":\"Informativa sulla Privacy - Bonfiglioli Consulting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\"},\"datePublished\":\"2026-07-17T08:34:00+00:00\",\"dateModified\":\"2026-07-17T10:50:42+00:00\",\"description\":\"Consulta l'informativa sulla privacy del sito Bonfiglioli Consulting, ai sensi dell\u2019art. 13 del D. Lgs 196\\\/2003 e dell\u2019art. 13 del Regolamento 2016\\\/679\\\/UE.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/informativa-privacy-eventi-organizzati-in-collaborazione-con-partner\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/\",\"name\":\"Bonfiglioli Consulting\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informativa sulla Privacy - Bonfiglioli Consulting","description":"Consulta l'informativa sulla privacy del sito Bonfiglioli Consulting, ai sensi dell\u2019art. 13 del D. Lgs 196\/2003 e dell\u2019art. 13 del Regolamento 2016\/679\/UE.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonfiglioliconsulting.com\/it\/informativa-privacy-eventi-organizzati-in-collaborazione-con-partner\/","og_locale":"it_IT","og_type":"article","og_title":"Informativa sulla Privacy - Bonfiglioli Consulting","og_description":"Consulta l'informativa sulla privacy del sito Bonfiglioli Consulting, ai sensi dell\u2019art. 13 del D. Lgs 196\/2003 e dell\u2019art. 13 del Regolamento 2016\/679\/UE.","og_url":"https:\/\/www.bonfiglioliconsulting.com\/it\/informativa-privacy-eventi-organizzati-in-collaborazione-con-partner\/","og_site_name":"Bonfiglioli Consulting","article_modified_time":"2026-07-17T10:50:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bonfiglioliconsulting.com\/informativa-privacy-eventi-organizzati-in-collaborazione-con-partner\/","url":"https:\/\/www.bonfiglioliconsulting.com\/informativa-privacy-eventi-organizzati-in-collaborazione-con-partner\/","name":"Informativa sulla Privacy - Bonfiglioli Consulting","isPartOf":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website"},"datePublished":"2026-07-17T08:34:00+00:00","dateModified":"2026-07-17T10:50:42+00:00","description":"Consulta l'informativa sulla privacy del sito Bonfiglioli Consulting, ai sensi dell\u2019art. 13 del D. Lgs 196\/2003 e dell\u2019art. 13 del Regolamento 2016\/679\/UE.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bonfiglioliconsulting.com\/informativa-privacy-eventi-organizzati-in-collaborazione-con-partner\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website","url":"https:\/\/www.bonfiglioliconsulting.com\/it\/","name":"Bonfiglioli Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonfiglioliconsulting.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"atf_populated":false,"_links":{"self":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/pages\/74730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/comments?post=74730"}],"version-history":[{"count":5,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/pages\/74730\/revisions"}],"predecessor-version":[{"id":74738,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/pages\/74730\/revisions\/74738"}],"wp:attachment":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/media?parent=74730"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/tags?post=74730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}