{"id":61541,"date":"2025-07-24T11:22:58","date_gmt":"2025-07-24T09:22:58","guid":{"rendered":"https:\/\/www.bonfiglioliconsulting.com\/it\/?post_type=course&#038;p=61541"},"modified":"2025-12-10T10:48:30","modified_gmt":"2025-12-10T09:48:30","slug":"lean-agent","status":"publish","type":"course","link":"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/lean-agent\/","title":{"rendered":"Lean Agent"},"content":{"rendered":"<div id=\"saz-block-block_b0ba0039062456f756205127df14f3b9\" class=\"saz-block saz-block-acf-onda \" style=\"background-color: #ffffff\">\n    <div class=\"container-fluid\">\n                    <div class=\"row\">\n                <div class=\"col-lg-9 pl-0\">\n                    <svg id=\"onda-blocchi\" class=\"reverse\" data-name=\"onda\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 180\"><path class=\"cls-1\" d=\"M0,180H1000V.4S458.72-.5,279.85.4c-49,.25-68.29,7.31-161.7,105.9C94.46,131.3,49.5,174.7,0,180Z\" transform=\"translate(0 0)\" style=\"fill: #e3e9ed\"\/><\/svg>\n                <\/div>\n            <\/div>\n            <\/div>\n<\/div><div id=\"saz-block-id-EumtmIRoeZ1b\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div>\n\n<div id=\"saz-block-block_ea0fa6f717232a1cf70d499ba60e2403\" class=\"saz-block saz-block-acf-piazza-servizi  bg-servizi pt-5\" style=\"background-color: #e3e9ed;\">\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-12\">\n                                    <h3 class=\"text-dark mb-5\">I moduli sono fruibili anche singolarmente | Scoprili qui!<\/h3>\n                            <\/div>\n\n                                                                                        \n<div class=\"col-md-6 col-lg-3\">\n    <div class=\"card card-servizi mb-4\">\n                    <a href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/lean-problem-solving\/\"><img decoding=\"async\" width=\"600\" height=\"338\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/Banner-problem-solving-1-600x338.jpg\" class=\"img-fluid wp-post-image lazyload\" alt=\"Una lampadina incandescente si trova su una superficie di legno, circondata da ghirigori legati al business e alle idee, come grafici, diagrammi, pezzi di puzzle e testi come Problem Solving, Thinking Outside The Box e CREATIVITY su uno sfondo scuro.\" data-srcset=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/Banner-problem-solving-1-600x338.jpg 600w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/Banner-problem-solving-1-750x422.jpg 750w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/Banner-problem-solving-1-1024x576.jpg 1024w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/Banner-problem-solving-1-1536x864.jpg 1536w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/Banner-problem-solving-1-2048x1152.jpg 2048w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/Banner-problem-solving-1-18x10.jpg 18w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/338;\" \/><\/a>\n                <div class=\"card-body mt-3\">\n                                    \n                \n                    <div class=\"text-uppercase has-extrasmall-font-size mb-2 categoria-servizi\"><a href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/tipologie\/corsi-di-formazione\/corsi-on-demand\/operational-excellence\/\">Corsi Operational Excellence<\/a><\/div>\n\n                \n            \n            <h3 class=\"has-medium-font-size my-2 mt-xl-0 mb-xl-3\"><a class=\"text-primary\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/lean-problem-solving\/\">Corso &#8220;Problem Setting &amp; Problem Solving: analisi e soluzione definitiva&#8221;<\/a><\/h3>\n\n            \n\t                        <p class=\"text-secondary has-small-font-size\"><\/p>\n\t        \n                    <\/div>\n    <\/div>\n<\/div>                                                                                \n<div class=\"col-md-6 col-lg-3\">\n    <div class=\"card card-servizi mb-4\">\n                    <a href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/creare-abitudini-per-il-miglioramento-continuo\/\"><img decoding=\"async\" width=\"600\" height=\"343\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/1680909-600x343.png\" class=\"img-fluid wp-post-image lazyload\" alt=\"Un gruppo di professionisti in un ufficio moderno discute di un grafico crescente su uno schermo ricoperto di post-it colorati, che riflette le abitudini di lavoro di squadra e di brainstorming per il miglioramento continuo durante una riunione di lavoro.\" data-srcset=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/1680909-600x343.png 600w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/1680909-750x429.png 750w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/1680909-1024x585.png 1024w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/1680909.png 1344w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/343;\" \/><\/a>\n                <div class=\"card-body mt-3\">\n                                    \n                \n                    <div class=\"text-uppercase has-extrasmall-font-size mb-2 categoria-servizi\"><a href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/tipologie\/corsi-di-formazione\/corsi-on-demand\/corsi-people-development\/\">Corsi People Development<\/a><\/div>\n\n                \n            \n            <h3 class=\"has-medium-font-size my-2 mt-xl-0 mb-xl-3\"><a class=\"text-primary\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/creare-abitudini-per-il-miglioramento-continuo\/\">Corso &#8220;Creare abitudini per il miglioramento continuo&#8221;<\/a><\/h3>\n\n            \n\t                        <p class=\"text-secondary has-small-font-size\"><\/p>\n\t        \n                    <\/div>\n    <\/div>\n<\/div>                                                                                \n<div class=\"col-md-6 col-lg-3\">\n    <div class=\"card card-servizi mb-4\">\n                    <a href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/corso-mappatura-flussi-processi\/\"><img decoding=\"async\" width=\"600\" height=\"343\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2025\/11\/1710231-600x343.png\" class=\"img-fluid wp-post-image lazyload\" alt=\"Bonfiglioli Consulting \u2013 consulenza lean e innovazione d&#039;impresa\" data-srcset=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2025\/11\/1710231-600x343.png 600w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2025\/11\/1710231-750x429.png 750w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2025\/11\/1710231-1024x585.png 1024w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2025\/11\/1710231-18x10.png 18w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2025\/11\/1710231.png 1344w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/343;\" \/><\/a>\n                <div class=\"card-body mt-3\">\n                                    \n                \n                    <div class=\"text-uppercase has-extrasmall-font-size mb-2 categoria-servizi\"><a href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/tipologie\/corsi-di-formazione\/corsi-on-demand\/operational-excellence\/\">Corsi Operational Excellence<\/a><\/div>\n\n                \n            \n            <h3 class=\"has-medium-font-size my-2 mt-xl-0 mb-xl-3\"><a class=\"text-primary\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/corso-mappatura-flussi-processi\/\">Corso &#8220;Process Mapping: tecniche e strumenti per la Mappatura dei Flussi&#8221;<\/a><\/h3>\n\n            \n\t                        <p class=\"text-secondary has-small-font-size\"><\/p>\n\t        \n                    <\/div>\n    <\/div>\n<\/div>                                                                                \n<div class=\"col-md-6 col-lg-3\">\n    <div class=\"card card-servizi mb-4\">\n                    <a href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/lean-project-management\/\"><img decoding=\"async\" width=\"600\" height=\"343\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/Corso-LFS-Project-Management-600x343.png\" class=\"img-fluid wp-post-image lazyload\" alt=\"Due persone che lavorano intensamente al computer in un ufficio moderno, circondate da grafici e diagrammi digitali luminosi, creando un&#039;atmosfera analitica e high-tech incentrata sulla gestione efficiente dei progetti.\" data-srcset=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/Corso-LFS-Project-Management-600x343.png 600w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/Corso-LFS-Project-Management-750x429.png 750w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/Corso-LFS-Project-Management-1024x585.png 1024w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/Corso-LFS-Project-Management.png 1344w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/343;\" \/><\/a>\n                <div class=\"card-body mt-3\">\n                                    \n                \n                    <div class=\"text-uppercase has-extrasmall-font-size mb-2 categoria-servizi\"><a href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/tipologie\/corsi-di-formazione\/corsi-on-demand\/corsi-people-development\/\">Corsi People Development<\/a><\/div>\n\n                \n            \n            <h3 class=\"has-medium-font-size my-2 mt-xl-0 mb-xl-3\"><a class=\"text-primary\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/lean-project-management\/\">Corso &#8220;Project Management&#8221;<\/a><\/h3>\n\n            \n\t                        <p class=\"text-secondary has-small-font-size\"><\/p>\n\t        \n                    <\/div>\n    <\/div>\n<\/div>                            \n                    <\/div>\n    <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":null,"protected":false},"featured_media":61545,"menu_order":10013,"template":"","tipologia":[96],"content_type":[154],"class_list":["post-61541","course","type-course","status-publish","has-post-thumbnail","hentry","tipologia-lean-excellence","content_type-corso"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lean Agent: chiave per il cambiamento | Bonfiglioli Consulting<\/title>\n<meta name=\"description\" content=\"Lean Agent \u2013 Diventa un agente del cambiamento, promuovendo il Lean Thinking e il miglioramento continuo nella tua azienda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/lean-agent\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lean Agent: chiave per il cambiamento | Bonfiglioli Consulting\" \/>\n<meta property=\"og:description\" content=\"Lean Agent \u2013 Diventa un agente del cambiamento, promuovendo il Lean Thinking e il miglioramento continuo nella tua azienda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/lean-agent\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonfiglioli Consulting\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-10T09:48:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2024\/10\/AdobeStock_492497575-1-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/lean-agent\\\/\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/lean-agent\\\/\",\"name\":\"Lean Agent: chiave per il cambiamento | Bonfiglioli Consulting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/lean-agent\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/lean-agent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/AdobeStock_492497575-1-scaled.jpeg\",\"datePublished\":\"2025-07-24T09:22:58+00:00\",\"dateModified\":\"2025-12-10T09:48:30+00:00\",\"description\":\"Lean Agent \u2013 Diventa un agente del cambiamento, promuovendo il Lean Thinking e il miglioramento continuo nella tua azienda.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/lean-agent\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/lean-agent\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/AdobeStock_492497575-1-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/AdobeStock_492497575-1-scaled.jpeg\",\"width\":2560,\"height\":1440,\"caption\":\"Bonfiglioli Consulting \u2013 consulenza lean e innovazione d'impresa\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/\",\"name\":\"Bonfiglioli Consulting\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lean Agent: chiave per il cambiamento | Bonfiglioli Consulting","description":"Lean Agent \u2013 Diventa un agente del cambiamento, promuovendo il Lean Thinking e il miglioramento continuo nella tua azienda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/lean-agent\/","og_locale":"it_IT","og_type":"article","og_title":"Lean Agent: chiave per il cambiamento | Bonfiglioli Consulting","og_description":"Lean Agent \u2013 Diventa un agente del cambiamento, promuovendo il Lean Thinking e il miglioramento continuo nella tua azienda.","og_url":"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/lean-agent\/","og_site_name":"Bonfiglioli Consulting","article_modified_time":"2025-12-10T09:48:30+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2024\/10\/AdobeStock_492497575-1-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/lean-agent\/","url":"https:\/\/www.bonfiglioliconsulting.com\/events\/lean-agent\/","name":"Lean Agent: chiave per il cambiamento | Bonfiglioli Consulting","isPartOf":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/lean-agent\/#primaryimage"},"image":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/lean-agent\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2024\/10\/AdobeStock_492497575-1-scaled.jpeg","datePublished":"2025-07-24T09:22:58+00:00","dateModified":"2025-12-10T09:48:30+00:00","description":"Lean Agent \u2013 Diventa un agente del cambiamento, promuovendo il Lean Thinking e il miglioramento continuo nella tua azienda.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bonfiglioliconsulting.com\/events\/lean-agent\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/lean-agent\/#primaryimage","url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2024\/10\/AdobeStock_492497575-1-scaled.jpeg","contentUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2024\/10\/AdobeStock_492497575-1-scaled.jpeg","width":2560,"height":1440,"caption":"Bonfiglioli Consulting \u2013 consulenza lean e innovazione d'impresa"},{"@type":"WebSite","@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website","url":"https:\/\/www.bonfiglioliconsulting.com\/it\/","name":"Bonfiglioli Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonfiglioliconsulting.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"atf_populated":false,"_links":{"self":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/course\/61541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/types\/course"}],"version-history":[{"count":14,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/course\/61541\/revisions"}],"predecessor-version":[{"id":71034,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/course\/61541\/revisions\/71034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/media\/61545"}],"wp:attachment":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/media?parent=61541"}],"wp:term":[{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/tipologia?post=61541"},{"taxonomy":"content_type","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/content_type?post=61541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}