{"id":59383,"date":"2024-08-01T15:29:00","date_gmt":"2024-08-01T13:29:00","guid":{"rendered":"https:\/\/www.bonfiglioliconsulting.com\/it\/?post_type=course&#038;p=59383"},"modified":"2025-11-13T07:15:52","modified_gmt":"2025-11-13T06:15:52","slug":"digital-talk-ia-in-azione-ottimizzare-e-rendere-efficace-le-supply-chain-nellera-digitale","status":"publish","type":"course","link":"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/digital-talk-ia-in-azione-ottimizzare-e-rendere-efficace-le-supply-chain-nellera-digitale\/","title":{"rendered":"Digital Talk | IA in Azione: Ottimizzare e rendere efficace la Supply Chain nell&#8217;era digitale"},"content":{"rendered":"<div id=\"saz-block-block_8a8ff98cced67730fc74e3dfbed44b73\" class=\"saz-block saz-block-acf-onda \" style=\"background-color: #ffffff\">\n    <div class=\"container-fluid\">\n                    <div class=\"row\">\n                <div class=\"col-lg-9 pl-0\">\n                    <svg id=\"onda-blocchi\" class=\"reverse\" data-name=\"onda\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 180\"><path class=\"cls-1\" d=\"M0,180H1000V.4S458.72-.5,279.85.4c-49,.25-68.29,7.31-161.7,105.9C94.46,131.3,49.5,174.7,0,180Z\" transform=\"translate(0 0)\" style=\"fill: #32468c\"\/><\/svg>\n                <\/div>\n            <\/div>\n            <\/div>\n<\/div><div id=\"saz-block-id-KcLiEtNJaHzK\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-8FnslU1dK4fm\" class=\"saz-block saz-block-core-heading saz-block-style-array saz-block-backgroundcolor-primary saz-block-textcolor-white saz-block-classname-wp-elements-1\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<h2 class=\"wp-block-heading has-white-color has-primary-background-color has-text-color has-background has-link-color wp-elements-1\"><strong>Speaker<\/strong><\/h2>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-lBERoQVoWMkz\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-1TM9tD21EQPt\" class=\"saz-block saz-block-core-columns saz-block-verticalalignment-center saz-block-align-wide saz-block-classname-pt-4-pb-5-wp-elements-2 saz-block-style-array saz-block-backgroundcolor-primary saz-block-textcolor-white\"><div class=\"container\"><div class=\"row\">\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center pt-4 pb-5 has-white-color has-primary-background-color has-text-color has-background has-link-color wp-elements-2 is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><div id=\"saz-block-id-59392\" class=\"saz-block saz-block-core-image saz-block-id-array saz-block-width-176px saz-block-sizeslug-full saz-block-linkdestination-none saz-block-classname-is-style-rounded\">\n<figure class=\"wp-block-image size-full is-resized is-style-rounded\"><img decoding=\"async\" width=\"500\" height=\"500\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2024\/08\/SCAGLIARINI.jpg\" alt=\"\" class=\"wp-image-59392 lazyload\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/500;width:176px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:70%\"><div id=\"saz-block-id-NHaI4s3FRmpt\" class=\"saz-block saz-block-core-heading saz-block-level-array saz-block-style-array saz-block-textcolor-white saz-block-fontsize-medium saz-block-classname-wp-elements-3\">\n<h3 class=\"wp-block-heading has-white-color has-text-color has-link-color has-medium-font-size wp-elements-3\"><strong>LUCA SCAGLIARINI<\/strong> | BONFIGLIOLI CONSULTING<br>Director Digital Competence Center<\/h3>\n<\/div>\n\n<div id=\"saz-block-id-kbkRrgBqVYZv\" class=\"saz-block saz-block-core-paragraph\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\n<div id=\"saz-block-id-QGEh2OmQ0SIb\" class=\"saz-block saz-block-core-paragraph\">\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.linkedin.com\/in\/scagliarini\/\">LinkedIn<\/a><\/p>\n<\/div><\/div>\n<\/div>\n<\/div><\/div><\/div><div id=\"saz-block-id-CdeKbX7zcxvW\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-KdaYKBt0ELQq\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":null,"protected":false},"featured_media":59384,"menu_order":20200,"template":"","tipologia":[50],"content_type":[155],"class_list":["post-59383","course","type-course","status-publish","has-post-thumbnail","hentry","tipologia-workshop-digital-talk","content_type-evento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IA in Azione: Ottimizzare la Supply Chain nell\u2019era digitale<\/title>\n<meta name=\"description\" content=\"Ottimizzare la supply chain nell&#039;era digitale \u2013 Come l&#039;intelligenza artificiale pu\u00f2 rendere la supply chain pi\u00f9 efficiente e resiliente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/digital-talk-ia-in-azione-ottimizzare-e-rendere-efficace-le-supply-chain-nellera-digitale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IA in Azione: Ottimizzare la Supply Chain nell\u2019era digitale\" \/>\n<meta property=\"og:description\" content=\"Ottimizzare la supply chain nell&#039;era digitale \u2013 Come l&#039;intelligenza artificiale pu\u00f2 rendere la supply chain pi\u00f9 efficiente e resiliente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/digital-talk-ia-in-azione-ottimizzare-e-rendere-efficace-le-supply-chain-nellera-digitale\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonfiglioli Consulting\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T06:15:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2024\/08\/banner_2024_09_18-1024x578.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"578\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/digital-talk-ia-in-azione-ottimizzare-e-rendere-efficace-le-supply-chain-nellera-digitale\\\/\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/digital-talk-ia-in-azione-ottimizzare-e-rendere-efficace-le-supply-chain-nellera-digitale\\\/\",\"name\":\"IA in Azione: Ottimizzare la Supply Chain nell\u2019era digitale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/digital-talk-ia-in-azione-ottimizzare-e-rendere-efficace-le-supply-chain-nellera-digitale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/digital-talk-ia-in-azione-ottimizzare-e-rendere-efficace-le-supply-chain-nellera-digitale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/banner_2024_09_18.png\",\"datePublished\":\"2024-08-01T13:29:00+00:00\",\"dateModified\":\"2025-11-13T06:15:52+00:00\",\"description\":\"Ottimizzare la supply chain nell'era digitale \u2013 Come l'intelligenza artificiale pu\u00f2 rendere la supply chain pi\u00f9 efficiente e resiliente.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/digital-talk-ia-in-azione-ottimizzare-e-rendere-efficace-le-supply-chain-nellera-digitale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/digital-talk-ia-in-azione-ottimizzare-e-rendere-efficace-le-supply-chain-nellera-digitale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/banner_2024_09_18.png\",\"contentUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/banner_2024_09_18.png\",\"width\":4407,\"height\":2489,\"caption\":\"Banner 2024 09 18 \u2013 Bonfiglioli Consulting\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/\",\"name\":\"Bonfiglioli Consulting\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IA in Azione: Ottimizzare la Supply Chain nell\u2019era digitale","description":"Ottimizzare la supply chain nell'era digitale \u2013 Come l'intelligenza artificiale pu\u00f2 rendere la supply chain pi\u00f9 efficiente e resiliente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/digital-talk-ia-in-azione-ottimizzare-e-rendere-efficace-le-supply-chain-nellera-digitale\/","og_locale":"it_IT","og_type":"article","og_title":"IA in Azione: Ottimizzare la Supply Chain nell\u2019era digitale","og_description":"Ottimizzare la supply chain nell'era digitale \u2013 Come l'intelligenza artificiale pu\u00f2 rendere la supply chain pi\u00f9 efficiente e resiliente.","og_url":"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/digital-talk-ia-in-azione-ottimizzare-e-rendere-efficace-le-supply-chain-nellera-digitale\/","og_site_name":"Bonfiglioli Consulting","article_modified_time":"2025-11-13T06:15:52+00:00","og_image":[{"width":1024,"height":578,"url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2024\/08\/banner_2024_09_18-1024x578.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/digital-talk-ia-in-azione-ottimizzare-e-rendere-efficace-le-supply-chain-nellera-digitale\/","url":"https:\/\/www.bonfiglioliconsulting.com\/events\/digital-talk-ia-in-azione-ottimizzare-e-rendere-efficace-le-supply-chain-nellera-digitale\/","name":"IA in Azione: Ottimizzare la Supply Chain nell\u2019era digitale","isPartOf":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/digital-talk-ia-in-azione-ottimizzare-e-rendere-efficace-le-supply-chain-nellera-digitale\/#primaryimage"},"image":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/digital-talk-ia-in-azione-ottimizzare-e-rendere-efficace-le-supply-chain-nellera-digitale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2024\/08\/banner_2024_09_18.png","datePublished":"2024-08-01T13:29:00+00:00","dateModified":"2025-11-13T06:15:52+00:00","description":"Ottimizzare la supply chain nell'era digitale \u2013 Come l'intelligenza artificiale pu\u00f2 rendere la supply chain pi\u00f9 efficiente e resiliente.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bonfiglioliconsulting.com\/events\/digital-talk-ia-in-azione-ottimizzare-e-rendere-efficace-le-supply-chain-nellera-digitale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/digital-talk-ia-in-azione-ottimizzare-e-rendere-efficace-le-supply-chain-nellera-digitale\/#primaryimage","url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2024\/08\/banner_2024_09_18.png","contentUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2024\/08\/banner_2024_09_18.png","width":4407,"height":2489,"caption":"Banner 2024 09 18 \u2013 Bonfiglioli Consulting"},{"@type":"WebSite","@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website","url":"https:\/\/www.bonfiglioliconsulting.com\/it\/","name":"Bonfiglioli Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonfiglioliconsulting.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"atf_populated":false,"_links":{"self":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/course\/59383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/types\/course"}],"version-history":[{"count":9,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/course\/59383\/revisions"}],"predecessor-version":[{"id":61681,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/course\/59383\/revisions\/61681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/media\/59384"}],"wp:attachment":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/media?parent=59383"}],"wp:term":[{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/tipologia?post=59383"},{"taxonomy":"content_type","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/content_type?post=59383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}