{"id":53795,"date":"2024-02-06T10:46:13","date_gmt":"2024-02-06T09:46:13","guid":{"rendered":"https:\/\/www.bcsoa.it\/?post_type=course&#038;p=53795"},"modified":"2025-11-13T07:04:46","modified_gmt":"2025-11-13T06:04:46","slug":"india-experience-tour","status":"publish","type":"course","link":"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/india-experience-tour\/","title":{"rendered":"India Experience Tour"},"content":{"rendered":"<div id=\"saz-block-block_0b96014e4c1f2a6795cd13fea5d5a88d\" class=\"saz-block saz-block-acf-onda \" style=\"background-color: #ffffff\">\n    <div class=\"container-fluid\">\n                    <div class=\"row\">\n                <div class=\"col-lg-9 pl-0\">\n                    <svg id=\"onda-blocchi\" class=\"reverse\" data-name=\"onda\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 180\"><path class=\"cls-1\" d=\"M0,180H1000V.4S458.72-.5,279.85.4c-49,.25-68.29,7.31-161.7,105.9C94.46,131.3,49.5,174.7,0,180Z\" transform=\"translate(0 0)\" style=\"fill: #e3e9ed\"\/><\/svg>\n                <\/div>\n            <\/div>\n            <\/div>\n<\/div><div id=\"saz-block-id-jRMYv338tkud\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div>\n\n<div id=\"saz-block-block_df918b00e306fe87d997acd6343295f3\" class=\"saz-block saz-block-acf-blocco-approfondimento  bg-servizi pt-5 pb-4\" style=\"background-color:#e3e9ed\">\n    <div class=\"container\">\n        <div class=\"row\"> \n            <div class=\"col-12 col-lg-8\">\n                                    <h3 class=\"text-gray mb-5 mt-lg-3\">Il valore aggiunto dell&#8217;Experience Tour in India<\/h3>\n                                <\/div>\n        <\/div>\n                    <div class=\"row\">\n                                                                        <div class=\"col-12 col-md-6 col-lg\">\n                        <div class=\"card card-testimonial mb-5\">\n                            <div class=\"card-body\">\n                                <div class=\"d-inline-flex align-items-center mb-3\">\n                                                                            <img decoding=\"async\" class=\"img-fluid lazyload\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/icona-formazione.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 66px; --smush-placeholder-aspect-ratio: 66\/76;\">\n                                                                                                                <h3 class=\"text-gray text-uppercase d-inline pl-3 mb-0 has-medium-font-size\">FORMAZIONE<\/h3>\n                                                                    <\/div>\n\n                                \n                                                                    <div class=\"text-gray mb-4 has-small-font-size card-body-height\">Conoscere dall\u2019interno il pi\u00f9 promettente Paese del mercato globale\r\ne toccare con mano le moderne tecnologie del Sub-Continente per comprendere le opportunit\u00e0 economiche del mercato domestico.<\/div>\n                                \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                                                                        <div class=\"col-12 col-md-6 col-lg\">\n                        <div class=\"card card-testimonial mb-5\">\n                            <div class=\"card-body\">\n                                <div class=\"d-inline-flex align-items-center mb-3\">\n                                                                            <img decoding=\"async\" class=\"img-fluid lazyload\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/icona-esperienza.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 60px; --smush-placeholder-aspect-ratio: 60\/73;\">\n                                                                                                                <h3 class=\"text-gray text-uppercase d-inline pl-3 mb-0 has-medium-font-size\">ESPERIENZA<\/h3>\n                                                                    <\/div>\n\n                                \n                                                                    <div class=\"text-gray mb-4 has-small-font-size card-body-height\">Briefing e debriefing di gruppo quotidiani per trarre il maggiore beneficio possibile dall\u2019esperienza e interazione diretta con le dinamiche culturali e di management locali.<\/div>\n                                \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                                                                        <div class=\"col-12 col-md-6 col-lg\">\n                        <div class=\"card card-testimonial mb-5\">\n                            <div class=\"card-body\">\n                                <div class=\"d-inline-flex align-items-center mb-3\">\n                                                                            <img decoding=\"async\" class=\"img-fluid lazyload\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/icona-networking.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 69px; --smush-placeholder-aspect-ratio: 69\/70;\">\n                                                                                                                <h3 class=\"text-gray text-uppercase d-inline pl-3 mb-0 has-medium-font-size\">NETWORKING<\/h3>\n                                                                    <\/div>\n\n                                \n                                                                    <div class=\"text-gray mb-4 has-small-font-size card-body-height\">Creare il proprio network di relazioni grazie a incontri con esperti, voci autorevoli e rappresentanti del mondo delle istituzioni <\/div>\n                                \n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                                            <\/div>\n                \n    <\/div>\n<\/div><div id=\"saz-block-id-1QLxIGOeGyFJ\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-block_b5cdffa5a36935e37fb08252b6a3105f\" class=\"saz-block saz-block-acf-onda \" style=\"background-color: #e3e9ed\">\n    <div class=\"container-fluid\">\n                    <div class=\"row\">\n                <div class=\"col-lg-9 offset-lg-3 pr-0 text-right\">\n                    <svg id=\"onda-blocchi\" data-name=\"onda\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 180\"><path class=\"cls-1\" d=\"M0,180H1000V.4S458.72-.5,279.85.4c-49,.25-68.29,7.31-161.7,105.9C94.46,131.3,49.5,174.7,0,180Z\" transform=\"translate(0 0)\" style=\"fill: #ffffff\"\/><\/svg>\n                <\/div>\n            <\/div>\n            <\/div>\n<\/div><div id=\"saz-block-id-nKP40NcSBizv\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div>\n\n<div id=\"saz-block-block_14e113ef4338c32cd9ae745f1239be91\" class=\"saz-block saz-block-acf-piazza-servizi  bg-servizi pt-5\" style=\"background-color: #ffffff;\">\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-12\">\n                                    <h3 class=\"text-dark mb-5\">SCOPRI LE EDIZIONI PASSATE<\/h3>\n                            <\/div>\n\n                                                                                        \n<div class=\"col-md-6 col-lg-4\">\n    <div class=\"card card-servizi mb-4\">\n                    <a href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/india-experience-tour-2024\/\"><img decoding=\"async\" width=\"600\" height=\"337\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/10\/2024-BANNER-INDIA-EXPERIENCE-TOUR-600x337.png\" class=\"img-fluid wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/10\/2024-BANNER-INDIA-EXPERIENCE-TOUR-600x337.png 600w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/10\/2024-BANNER-INDIA-EXPERIENCE-TOUR-750x422.png 750w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/10\/2024-BANNER-INDIA-EXPERIENCE-TOUR-1024x576.png 1024w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/10\/2024-BANNER-INDIA-EXPERIENCE-TOUR.png 1215w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/337;\" \/><\/a>\n                <div class=\"card-body mt-3\">\n                                    \n            <h3 class=\"has-medium-font-size my-2 mt-xl-0 mb-xl-3\"><a class=\"text-primary\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/india-experience-tour-2024\/\">India | Experience Tour 2024<\/a><\/h3>\n\n            \n\t                        <p class=\"text-secondary has-small-font-size\"><\/p>\n\t        \n                    <\/div>\n    <\/div>\n<\/div>                                                                                \n<div class=\"col-md-6 col-lg-4\">\n    <div class=\"card card-servizi mb-4\">\n                    <a href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/experience-tour-india-2023\/\"><img decoding=\"async\" width=\"600\" height=\"338\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/10\/2023-INDIA-EXPERIENCE-TOUR-600x338.png\" class=\"img-fluid wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/10\/2023-INDIA-EXPERIENCE-TOUR-600x338.png 600w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/10\/2023-INDIA-EXPERIENCE-TOUR-750x422.png 750w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/10\/2023-INDIA-EXPERIENCE-TOUR-1024x576.png 1024w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/10\/2023-INDIA-EXPERIENCE-TOUR.png 1280w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/338;\" \/><\/a>\n                <div class=\"card-body mt-3\">\n                                    \n            <h3 class=\"has-medium-font-size my-2 mt-xl-0 mb-xl-3\"><a class=\"text-primary\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/experience-tour-india-2023\/\">India | Experience Tour 2023<\/a><\/h3>\n\n            \n\t                        <p class=\"text-secondary has-small-font-size\"><\/p>\n\t        \n                    <\/div>\n    <\/div>\n<\/div>                            \n                    <\/div>\n    <\/div>\n<\/div><div id=\"saz-block-id-Yqt9710RHLtd\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-block_0b96014e4c1f2a6795cd13fea5d5a88d\" class=\"saz-block saz-block-acf-onda \" style=\"background-color: #ffffff\">\n    <div class=\"container-fluid\">\n                    <div class=\"row\">\n                <div class=\"col-lg-9 pl-0\">\n                    <svg id=\"onda-blocchi\" class=\"reverse\" data-name=\"onda\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 180\"><path class=\"cls-1\" d=\"M0,180H1000V.4S458.72-.5,279.85.4c-49,.25-68.29,7.31-161.7,105.9C94.46,131.3,49.5,174.7,0,180Z\" transform=\"translate(0 0)\" style=\"fill: #e3e9ed\"\/><\/svg>\n                <\/div>\n            <\/div>\n            <\/div>\n<\/div><div id=\"saz-block-id-vqXypi7IbIjr\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div>\n\n<div id=\"saz-block-block_0592195051f44908549eaf48db0ff0c7\" class=\"saz-block saz-block-acf-piazza-servizi  bg-servizi pt-5\" style=\"background-color: #e3e9ed;\">\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-12\">\n                                    <h3 class=\"text-dark mb-5\">Scopri tutti gli Study Tour<\/h3>\n                            <\/div>\n\n                                                                                        \n<div class=\"col-md-6 col-lg-4\">\n    <div class=\"card card-servizi mb-4\">\n                    <a href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/silicon-valley-study-tour\/\"><img decoding=\"async\" width=\"600\" height=\"338\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/07\/Silicon-Valley-Banner-600x338.jpg\" class=\"img-fluid wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/07\/Silicon-Valley-Banner-600x338.jpg 600w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/07\/Silicon-Valley-Banner-750x422.jpg 750w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/07\/Silicon-Valley-Banner-1024x576.jpg 1024w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/07\/Silicon-Valley-Banner-1536x864.jpg 1536w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/07\/Silicon-Valley-Banner-2048x1152.jpg 2048w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/338;\" \/><\/a>\n                <div class=\"card-body mt-3\">\n                                    \n                \n                    <div class=\"text-uppercase has-extrasmall-font-size mb-2 categoria-servizi\"><a href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/tipologie\/appuntamenti\/study-tour-estero\/\">Study Tour Estero<\/a><\/div>\n\n                \n            \n            <h3 class=\"has-medium-font-size my-2 mt-xl-0 mb-xl-3\"><a class=\"text-primary\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/silicon-valley-study-tour\/\">Silicon Valley Study Tour<\/a><\/h3>\n\n            \n\t                        <p class=\"text-secondary has-small-font-size\"><\/p>\n\t        \n                    <\/div>\n    <\/div>\n<\/div>                                                                                \n<div class=\"col-md-6 col-lg-4\">\n    <div class=\"card card-servizi mb-4\">\n                    <a href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/lean-japan-study-tour-2\/\"><img decoding=\"async\" width=\"600\" height=\"338\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/08\/BANNER-JAPAN-STUDY-TOUR-2025-600x338.jpg\" class=\"img-fluid wp-post-image lazyload\" alt=\"Un paesaggio urbano futuristico si fonde con l&#039;architettura tradizionale in Giappone, dove le scie luminose di un treno ad alta velocit\u00e0 sfrecciano oltre una pagoda. Sullo sfondo, una montagna innevata si erge maestosa sotto un cielo azzurro e limpido, offrendo uno sfondo ideale per un interessante viaggio di studio.\" data-srcset=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/08\/BANNER-JAPAN-STUDY-TOUR-2025-600x338.jpg 600w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/08\/BANNER-JAPAN-STUDY-TOUR-2025-750x422.jpg 750w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/08\/BANNER-JAPAN-STUDY-TOUR-2025-1024x576.jpg 1024w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/08\/BANNER-JAPAN-STUDY-TOUR-2025.jpg 1280w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/338;\" \/><\/a>\n                <div class=\"card-body mt-3\">\n                                    \n                \n                    <div class=\"text-uppercase has-extrasmall-font-size mb-2 categoria-servizi\"><a href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/tipologie\/appuntamenti\/study-tour-estero\/\">Study Tour Estero<\/a><\/div>\n\n                \n            \n            <h3 class=\"has-medium-font-size my-2 mt-xl-0 mb-xl-3\"><a class=\"text-primary\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/lean-japan-study-tour-2\/\">Lean Japan Study Tour<\/a><\/h3>\n\n            \n\t                        <p class=\"text-secondary has-small-font-size\"><\/p>\n\t        \n                    <\/div>\n    <\/div>\n<\/div>                                                                                \n<div class=\"col-md-6 col-lg-4\">\n    <div class=\"card card-servizi mb-4\">\n                    <a href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/germany-study-tour\/\"><img decoding=\"async\" width=\"600\" height=\"338\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/09\/Banner-Germany-Study-Tour-1-600x338.jpg\" class=\"img-fluid wp-post-image lazyload\" alt=\"\" data-srcset=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/09\/Banner-Germany-Study-Tour-1-600x338.jpg 600w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/09\/Banner-Germany-Study-Tour-1-750x422.jpg 750w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/09\/Banner-Germany-Study-Tour-1-1024x576.jpg 1024w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/09\/Banner-Germany-Study-Tour-1-1536x864.jpg 1536w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/09\/Banner-Germany-Study-Tour-1-2048x1152.jpg 2048w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/338;\" \/><\/a>\n                <div class=\"card-body mt-3\">\n                                    \n                \n                    <div class=\"text-uppercase has-extrasmall-font-size mb-2 categoria-servizi\"><a href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/tipologie\/appuntamenti\/study-tour-estero\/\">Study Tour Estero<\/a><\/div>\n\n                \n            \n            <h3 class=\"has-medium-font-size my-2 mt-xl-0 mb-xl-3\"><a class=\"text-primary\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/germany-study-tour\/\">Germany Study Tour<\/a><\/h3>\n\n            \n\t                        <p class=\"text-secondary has-small-font-size\"><\/p>\n\t        \n                    <\/div>\n    <\/div>\n<\/div>                            \n                    <\/div>\n    <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":null,"protected":false},"featured_media":62895,"menu_order":20596,"template":"","tipologia":[105],"content_type":[155],"class_list":["post-53795","course","type-course","status-publish","has-post-thumbnail","hentry","tipologia-study-tour-estero","content_type-evento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>India Experience Tour: sostenibilit\u00e0 | Bonfiglioli Consulting<\/title>\n<meta name=\"description\" content=\"L\u2019India Experience Tour \u00e8 il viaggio in India per vivere una full immersion di 5 giorni e ottenere le chiavi di accesso previlegiato in India.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/india-experience-tour\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"India Experience Tour: sostenibilit\u00e0 | Bonfiglioli Consulting\" \/>\n<meta property=\"og:description\" content=\"L\u2019India Experience Tour \u00e8 il viaggio in India per vivere una full immersion di 5 giorni e ottenere le chiavi di accesso previlegiato in India.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/india-experience-tour\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonfiglioli Consulting\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T06:04:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2024\/02\/Banner-India-Study-Tour-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1441\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/india-experience-tour\\\/\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/india-experience-tour\\\/\",\"name\":\"India Experience Tour: sostenibilit\u00e0 | Bonfiglioli Consulting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/india-experience-tour\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/india-experience-tour\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Banner-India-Study-Tour-scaled.jpg\",\"datePublished\":\"2024-02-06T09:46:13+00:00\",\"dateModified\":\"2025-11-13T06:04:46+00:00\",\"description\":\"L\u2019India Experience Tour \u00e8 il viaggio in India per vivere una full immersion di 5 giorni e ottenere le chiavi di accesso previlegiato in India.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/india-experience-tour\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/india-experience-tour\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Banner-India-Study-Tour-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Banner-India-Study-Tour-scaled.jpg\",\"width\":2560,\"height\":1441},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/\",\"name\":\"Bonfiglioli Consulting\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"India Experience Tour: sostenibilit\u00e0 | Bonfiglioli Consulting","description":"L\u2019India Experience Tour \u00e8 il viaggio in India per vivere una full immersion di 5 giorni e ottenere le chiavi di accesso previlegiato in India.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/india-experience-tour\/","og_locale":"it_IT","og_type":"article","og_title":"India Experience Tour: sostenibilit\u00e0 | Bonfiglioli Consulting","og_description":"L\u2019India Experience Tour \u00e8 il viaggio in India per vivere una full immersion di 5 giorni e ottenere le chiavi di accesso previlegiato in India.","og_url":"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/india-experience-tour\/","og_site_name":"Bonfiglioli Consulting","article_modified_time":"2025-11-13T06:04:46+00:00","og_image":[{"width":2560,"height":1441,"url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2024\/02\/Banner-India-Study-Tour-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/india-experience-tour\/","url":"https:\/\/www.bonfiglioliconsulting.com\/events\/india-experience-tour\/","name":"India Experience Tour: sostenibilit\u00e0 | Bonfiglioli Consulting","isPartOf":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/india-experience-tour\/#primaryimage"},"image":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/india-experience-tour\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2024\/02\/Banner-India-Study-Tour-scaled.jpg","datePublished":"2024-02-06T09:46:13+00:00","dateModified":"2025-11-13T06:04:46+00:00","description":"L\u2019India Experience Tour \u00e8 il viaggio in India per vivere una full immersion di 5 giorni e ottenere le chiavi di accesso previlegiato in India.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bonfiglioliconsulting.com\/events\/india-experience-tour\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/india-experience-tour\/#primaryimage","url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2024\/02\/Banner-India-Study-Tour-scaled.jpg","contentUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2024\/02\/Banner-India-Study-Tour-scaled.jpg","width":2560,"height":1441},{"@type":"WebSite","@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website","url":"https:\/\/www.bonfiglioliconsulting.com\/it\/","name":"Bonfiglioli Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonfiglioliconsulting.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"atf_populated":false,"_links":{"self":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/course\/53795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/types\/course"}],"version-history":[{"count":16,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/course\/53795\/revisions"}],"predecessor-version":[{"id":62896,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/course\/53795\/revisions\/62896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/media\/62895"}],"wp:attachment":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/media?parent=53795"}],"wp:term":[{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/tipologia?post=53795"},{"taxonomy":"content_type","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/content_type?post=53795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}