{"id":31020,"date":"2022-03-08T15:27:55","date_gmt":"2022-03-08T14:27:55","guid":{"rendered":"https:\/\/www.bcsoa.it\/?post_type=course&#038;p=31020"},"modified":"2025-11-13T07:07:23","modified_gmt":"2025-11-13T06:07:23","slug":"imprese-italiane-innovazione-cambiamento","status":"publish","type":"course","link":"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/imprese-italiane-innovazione-cambiamento\/","title":{"rendered":"Digital Roundtable | Innovation Excellence Study: i risultati della ricerca"},"content":{"rendered":"<div id=\"saz-block-block_9bca06528a59b1771d55686c232fb6fa\" class=\"saz-block saz-block-acf-onda \" style=\"background-color: #ffffff\">\n    <div class=\"container-fluid\">\n                    <div class=\"row\">\n                <div class=\"col-lg-9 pl-0\">\n                    <svg id=\"onda-blocchi\" class=\"reverse\" data-name=\"onda\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 180\"><path class=\"cls-1\" d=\"M0,180H1000V.4S458.72-.5,279.85.4c-49,.25-68.29,7.31-161.7,105.9C94.46,131.3,49.5,174.7,0,180Z\" transform=\"translate(0 0)\" style=\"fill: #e3e9ed\"\/><\/svg>\n                <\/div>\n            <\/div>\n            <\/div>\n<\/div><div id=\"saz-block-id-Nq75uvSnt3gb\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-00I8131u71Px\" class=\"saz-block saz-block-core-spacer saz-block-height-60px\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-ps9nVJfv13nb\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-ywSt0Le9lCII\" class=\"saz-block saz-block-core-heading\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<h2 class=\"wp-block-heading\"><strong>Keynote<\/strong> <strong>Speakers<\/strong><\/h2>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-tJgcLIQvdaPs\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-z8g3qG07WVwI\" class=\"saz-block saz-block-core-columns saz-block-verticalalignment-center saz-block-align-wide saz-block-classname-pt-4-pb-5\"><div class=\"container\"><div class=\"row\">\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center pt-4 pb-5 is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><div id=\"saz-block-id-31097\" class=\"saz-block saz-block-core-image saz-block-id-array saz-block-width-array saz-block-height-array saz-block-sizeslug-full saz-block-linkdestination-none saz-block-classname-is-style-rounded\">\n<figure class=\"wp-block-image size-full is-resized is-style-rounded\"><img decoding=\"async\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2022\/03\/1516246672077-1.jpg\" alt=\"\" class=\"wp-image-31097 lazyload\" width=\"176\" height=\"225\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 176px; --smush-placeholder-aspect-ratio: 176\/225;\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:70%\"><div id=\"saz-block-id-Ub3dJ5FjQXTx\" class=\"saz-block saz-block-core-paragraph saz-block-fontsize-medium\">\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong><a href=\"https:\/\/www.linkedin.com\/in\/alfredodemassis\/\" target=\"_blank\" rel=\"noreferrer noopener\">ALFREDO DE MASSIS<\/a> | Docente e Direttore del Centre for Family Business Management della Libera Universit\u00e0 di Bolzano<\/strong><\/p>\n<\/div>\n\n<div id=\"saz-block-id-tSkgkbxQiJDH\" class=\"saz-block saz-block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Professore Ordinario di Imprenditorialit\u00e0 e Family Business Management presso l\u2019Universit\u00e0 di Bolzano, dove dirige il Centro sul Family Business Management ed il Cluster su Imprenditorialit\u00e0, Innovazione e Management.<\/p>\n<\/div>\n\n<div id=\"saz-block-id-NmolArsnwFlI\" class=\"saz-block saz-block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Professore di Family Business presso il Centre for Family Business della Lancaster University Management School nel Regno Unito, offre contributi intellettuali presso IMD Business School in Svizzera.<\/p>\n<\/div>\n\n<div id=\"saz-block-id-u5aqH1RVhFZU\" class=\"saz-block saz-block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Presidente del board dell\u2019 Institute for Family Business della Zhejiang University in Cina, serve nei board di istituzioni italiane ed internazionali.<br>Nel Settembre 2015 \u00e8 stato annoverato tra i 25 migliori professori al mondo di Family Business dalla rivista specializzata di settore Family Capital e nel Marzo 2018 l\u2019International Family Enterprise Research Academy (in un rapporto sulle Rising Stars in Family Business Research ha incluso sei articoli di De Massis tra i pi\u00f9 influenti studi recenti sul family business al mondo).<\/p>\n<\/div>\n\n<div id=\"saz-block-id-HBJ9BetMV2gG\" class=\"saz-block saz-block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Nel 2022 \u00e8 riconosciuto da Family Capital tra i Top 100 Family Business Influencers a livello globale per la sua influenza sul mondo della pratica e della scienza delle imprese familiari.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div><\/div><\/div><div id=\"saz-block-id-qjUONkW3XyFw\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-k9P66kJUMmhb\" class=\"saz-block saz-block-core-columns saz-block-verticalalignment-center saz-block-align-wide saz-block-classname-pt-4-pb-5\"><div class=\"container\"><div class=\"row\">\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center pt-4 pb-5 is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><div id=\"saz-block-id-31685\" class=\"saz-block saz-block-core-image saz-block-id-array saz-block-width-array saz-block-sizeslug-full saz-block-linkdestination-none saz-block-classname-is-style-rounded\">\n<figure class=\"wp-block-image size-full is-resized is-style-rounded\"><img decoding=\"async\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2022\/03\/Maria-Raffaella-Caprioglio.jpg\" alt=\"\" class=\"wp-image-31685 lazyload\" width=\"176\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/600;\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:70%\"><div id=\"saz-block-id-fHoyd1WdTb3u\" class=\"saz-block saz-block-core-paragraph saz-block-fontsize-medium\">\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-primary-color\">MARIA RAFFAELLA CAPRIOGLIO<\/mark> |  Presidente di Umana SpA<\/strong><\/p>\n<\/div>\n\n<div id=\"saz-block-id-qlfqzTsv5N0r\" class=\"saz-block saz-block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Dal 2012 \u00e8 presidente di Umana. \u00c8 membro del Consiglio Generale di Confindustria nonch\u00e9 componente del Gruppo Tecnico Lavoro, Relazioni industriali e Welfare, e del Gruppo Tecnico Education. \u00c8 altres\u00ec componente del Consiglio Generale di Confindustria Venezia Rovigo, di Confindustria Belluno, dell\u2019Unione Industriale Pisana e di Assolombarda; per quest\u2019ultima \u00e8 inoltre membro del Consiglio direttivo del Gruppo Innovation Services e del Gruppo Tecnico Universit\u00e0 e Capitale Umano. \u00c8 inoltre membro del Consiglio e della Giunta della CCIAA di Venezia Rovigo e del Consiglio Unioncamere del Veneto, nonch\u00e9 Amministratore Unico di Camera Servizi. Siede nel Consiglio di Amministrazione di Certottica Scrl e di Dolomiti Cert.&nbsp;<\/p>\n<\/div><\/div>\n<\/div>\n<\/div><\/div><\/div><div id=\"saz-block-id-lCTdtfOCSeHT\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-l3GXvkMv1syr\" class=\"saz-block saz-block-core-columns saz-block-verticalalignment-center saz-block-align-wide saz-block-classname-pt-4-pb-5\"><div class=\"container\"><div class=\"row\">\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center pt-4 pb-5 is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><div id=\"saz-block-id-30473\" class=\"saz-block saz-block-core-image saz-block-id-array saz-block-width-array saz-block-sizeslug-full saz-block-linkdestination-none saz-block-classname-is-style-rounded\">\n<figure class=\"wp-block-image size-full is-resized is-style-rounded\"><img decoding=\"async\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2022\/02\/michele-round2.png\" alt=\"\" class=\"wp-image-30473 lazyload\" width=\"176\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 235px; --smush-placeholder-aspect-ratio: 235\/255;\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:70%\"><div id=\"saz-block-id-7VvhdDKoefnl\" class=\"saz-block saz-block-core-paragraph saz-block-fontsize-medium\">\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong><a href=\"https:\/\/www.linkedin.com\/in\/michelebonfiglioli\/\" target=\"_blank\" rel=\"noreferrer noopener\">MICHELE BONFIGLIOLI <\/a>| CEO, Bonfiglioli Consulting<\/strong><\/p>\n<\/div>\n\n<div id=\"saz-block-id-JejpkRrlGR9F\" class=\"saz-block saz-block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Laureato in Ingegneria Gestionale all\u2019Universit\u00e0 di Bologna, ha conseguito un Diploma in Business Administration presso Berkeley University, California (USA) e ha svolto attivit\u00e0 di Ricercatore in Manufacturing Engineering alla University of Nottingham.<br>Dal 2014 \u00e8 Amministratore Delegato di Bonfiglioli Consulting, inoltre \u00e8  fondatore della <a href=\"https:\/\/www.bonfiglioliconsulting.com\/lean-factory-school\/\">Lean Factory School\u00ae<\/a>. Ha ricoperto ruoli di rilievo e responsabilit\u00e0 in Confindustria.<\/p>\n<\/div>\n\n<div id=\"saz-block-id-rvRcCVzqxZpf\" class=\"saz-block saz-block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Autore di libri ed esperto dei temi Lean Thinking e Lean World Class\u00ae&nbsp;in particolare nei settori automotive, beni industriali, elettronico e farmaceutico. Ha organizzato importanti benchmarking studies internazionali ed \u00e8 riconosciuto come speaker internazionale sui temi di Operational Excellence.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div><\/div><\/div><div id=\"saz-block-id-auZ1YtcU1JoK\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-xWIRpsZs44zg\" class=\"saz-block saz-block-core-columns saz-block-verticalalignment-center saz-block-align-wide saz-block-classname-pt-4-pb-5\"><div class=\"container\"><div class=\"row\">\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center pt-4 pb-5 is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><div id=\"saz-block-id-31098\" class=\"saz-block saz-block-core-image saz-block-id-array saz-block-width-array saz-block-sizeslug-full saz-block-linkdestination-none saz-block-classname-is-style-rounded\">\n<figure class=\"wp-block-image size-full is-resized is-style-rounded\"><img decoding=\"async\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2022\/03\/IMG_0473.jpg\" alt=\"\" class=\"wp-image-31098 lazyload\" width=\"176\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 456px; --smush-placeholder-aspect-ratio: 456\/457;\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:70%\"><div id=\"saz-block-id-tDDqW2rbwTGk\" class=\"saz-block saz-block-core-paragraph saz-block-fontsize-medium\">\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong><a href=\"https:\/\/www.linkedin.com\/in\/edoardo-a-d-elia-479643170\/\" target=\"_blank\" rel=\"noreferrer noopener\">EDOARDO A. D&#8217;ELIA<\/a> |  Docente presso l&#8217;Universit\u00e0 di Bologna<\/strong><\/p>\n<\/div>\n\n<div id=\"saz-block-id-Dj6eKWhwOVdk\" class=\"saz-block saz-block-core-paragraph\">\n<p class=\"wp-block-paragraph\">Docente di Scrittura e Argomentazione e Public Speaking presso l\u2019Universit\u00e0 di Bologna; Docente di Business Communication presso la Bologna Business School (BBS); Docente di Comunicazione Multimediale presso l&#8217;Unicollege SSML di Mantova. Lavora come formatore e come moderatore in eventi in presenza e digitali. \u00c8 laureato in Scienze Filosofiche. Ha scritto&nbsp;<em>Parlare. Strumenti e tecniche del discorso<\/em>, Hoepli (2020).&nbsp;<\/p>\n<\/div><\/div>\n<\/div>\n<\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":null,"protected":false},"featured_media":31687,"menu_order":40711,"template":"","tipologia":[50,88],"content_type":[155],"class_list":["post-31020","course","type-course","status-publish","has-post-thumbnail","hentry","tipologia-workshop-digital-talk","tipologia-roundtable","content_type-evento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Innovation Excellence Study: i risultati della ricerca<\/title>\n<meta name=\"description\" content=\"Le imprese italiane sono pronte a raccogliere la sfida dell&#039;innovazione e del cambiamento \u2013 Come le aziende italiane le stanno affrontando.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/imprese-italiane-innovazione-cambiamento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Innovation Excellence Study: i risultati della ricerca\" \/>\n<meta property=\"og:description\" content=\"Le imprese italiane sono pronte a raccogliere la sfida dell&#039;innovazione e del cambiamento \u2013 Come le aziende italiane le stanno affrontando.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/imprese-italiane-innovazione-cambiamento\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonfiglioli Consulting\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T06:07:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2022\/03\/banner-innovation-excellence-study-V4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/imprese-italiane-innovazione-cambiamento\\\/\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/imprese-italiane-innovazione-cambiamento\\\/\",\"name\":\"Innovation Excellence Study: i risultati della ricerca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/imprese-italiane-innovazione-cambiamento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/imprese-italiane-innovazione-cambiamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/banner-innovation-excellence-study-V4.jpg\",\"datePublished\":\"2022-03-08T14:27:55+00:00\",\"dateModified\":\"2025-11-13T06:07:23+00:00\",\"description\":\"Le imprese italiane sono pronte a raccogliere la sfida dell'innovazione e del cambiamento \u2013 Come le aziende italiane le stanno affrontando.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/imprese-italiane-innovazione-cambiamento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/imprese-italiane-innovazione-cambiamento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/banner-innovation-excellence-study-V4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/banner-innovation-excellence-study-V4.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Banner Innovation Excellence Study \u2013 Bonfiglioli Consulting\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/\",\"name\":\"Bonfiglioli Consulting\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Innovation Excellence Study: i risultati della ricerca","description":"Le imprese italiane sono pronte a raccogliere la sfida dell'innovazione e del cambiamento \u2013 Come le aziende italiane le stanno affrontando.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/imprese-italiane-innovazione-cambiamento\/","og_locale":"it_IT","og_type":"article","og_title":"Innovation Excellence Study: i risultati della ricerca","og_description":"Le imprese italiane sono pronte a raccogliere la sfida dell'innovazione e del cambiamento \u2013 Come le aziende italiane le stanno affrontando.","og_url":"https:\/\/www.bonfiglioliconsulting.com\/it\/events\/imprese-italiane-innovazione-cambiamento\/","og_site_name":"Bonfiglioli Consulting","article_modified_time":"2025-11-13T06:07:23+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2022\/03\/banner-innovation-excellence-study-V4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/imprese-italiane-innovazione-cambiamento\/","url":"https:\/\/www.bonfiglioliconsulting.com\/events\/imprese-italiane-innovazione-cambiamento\/","name":"Innovation Excellence Study: i risultati della ricerca","isPartOf":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/imprese-italiane-innovazione-cambiamento\/#primaryimage"},"image":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/imprese-italiane-innovazione-cambiamento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2022\/03\/banner-innovation-excellence-study-V4.jpg","datePublished":"2022-03-08T14:27:55+00:00","dateModified":"2025-11-13T06:07:23+00:00","description":"Le imprese italiane sono pronte a raccogliere la sfida dell'innovazione e del cambiamento \u2013 Come le aziende italiane le stanno affrontando.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bonfiglioliconsulting.com\/events\/imprese-italiane-innovazione-cambiamento\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/imprese-italiane-innovazione-cambiamento\/#primaryimage","url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2022\/03\/banner-innovation-excellence-study-V4.jpg","contentUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2022\/03\/banner-innovation-excellence-study-V4.jpg","width":1280,"height":720,"caption":"Banner Innovation Excellence Study \u2013 Bonfiglioli Consulting"},{"@type":"WebSite","@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website","url":"https:\/\/www.bonfiglioliconsulting.com\/it\/","name":"Bonfiglioli Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonfiglioliconsulting.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"atf_populated":false,"_links":{"self":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/course\/31020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/types\/course"}],"version-history":[{"count":61,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/course\/31020\/revisions"}],"predecessor-version":[{"id":41289,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/course\/31020\/revisions\/41289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/media\/31687"}],"wp:attachment":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/media?parent=31020"}],"wp:term":[{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/tipologia?post=31020"},{"taxonomy":"content_type","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/it\/wp-json\/wp\/v2\/content_type?post=31020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}