{"id":23967,"date":"2021-05-07T11:49:16","date_gmt":"2021-05-07T09:49:16","guid":{"rendered":"https:\/\/www.bcsoa.it\/?page_id=23967"},"modified":"2025-08-28T15:43:37","modified_gmt":"2025-08-28T13:43:37","slug":"storci-spa","status":"publish","type":"page","link":"https:\/\/www.bonfiglioliconsulting.com\/en\/storci-spa\/","title":{"rendered":"Storci SpA"},"content":{"rendered":"<div id=\"saz-block-block_609507c1209b8\" class=\"d-none saz-block saz-block-acf-hero-servizi  bg-light bg-hero-servizi-eventi hero_overlay_parent vv lazyload\"\n     style=\"background:inherit; background-size:cover;\" data-bg=\"url(https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/05\/HERO-STORCI3.png) center top no-repeat transparent\">\n    <div class=\"hero_overlay\"><\/div>\n    <div class=\"container hero_content\">\n        <div class=\"row align-items-end\">\n            <div class=\"col-12\">\n                 \n                    <div class=\"mt-3 mb-2 text-dark\"><div class=\"breadcrumbs\"><span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" title=\"Vai a Bonfiglioli Consulting.\" href=\"https:\/\/www.bonfiglioliconsulting.com\/en\" class=\"home\"><span property=\"name\">Home<\/span><\/a><meta property=\"position\" content=\"1\"><\/span><\/div><script type=\"application\/ld+json\">{\"@context\":\"http:\/\/schema.org\",\"@type\":\"BreadcrumbList\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@id\":\"https:\/\/www.bonfiglioliconsulting.com\/en\",\"name\":\"Bonfiglioli Consulting\"}}]}<\/script><\/div>\n                                \n                                    <h1 class=\"has-huge-font-size font-weight-bold mb-0 text-primary\">Storci SpA<\/h1>\n                                                    <h2 class=\"has-medium-font-size my-3 font-weight-normal text-dark\">Processi snelli, robusti ed orientati ai risultati | Case Study<\/h2>\n                                <div class=\"mb-5 pb-4 pb-md-5\"><\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n    <svg class=\"onda-destra\" id=\"onda\" data-name=\"onda\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 180\"><path class=\"cls-1\" d=\"M0,180H1000V.4S458.72-.5,279.85.4c-49,.25-68.29,7.31-161.7,105.9C94.46,131.3,49.5,174.7,0,180Z\" transform=\"translate(0 0)\" style=\"fill: #ffffff\"\/><\/svg>\n<\/div>\n\n\n<section class=\"n_archive_hero lazyload\" style=\"background-image:inherit;\" data-bg-image=\"url(https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/05\/HERO-STORCI3.png)\"> \n    <div class=\"container h-100 position-relative\">\n        <div class=\"d-flex items-center h-100\">\n            <div class=\"n_archive_hero_content align-self-end text-white\">\n                <div class=\"text-white\">\n                <div class=\"breadcrumbs\">\n                 \n                    <div class=\"mt-3 mb-2 text-dark\"><div class=\"breadcrumbs\"><span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" title=\"Vai a Bonfiglioli Consulting.\" href=\"https:\/\/www.bonfiglioliconsulting.com\/en\" class=\"home\"><span property=\"name\">Home<\/span><\/a><meta property=\"position\" content=\"1\"><\/span><\/div><script type=\"application\/ld+json\">{\"@context\":\"http:\/\/schema.org\",\"@type\":\"BreadcrumbList\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@id\":\"https:\/\/www.bonfiglioliconsulting.com\/en\",\"name\":\"Bonfiglioli Consulting\"}}]}<\/script><\/div>\n                                <\/div>\n                <\/div>\n                \n                \n                \n                                      <h1 class=\"text-white text-primary\">Storci SpA<\/h1>\n                                \n                                    <div class=\"n_archive_desc\"> \n                     <p class=\"text-dark\">\n                       Processi snelli, robusti ed orientati ai risultati | Case Study                     <\/p>\n                    <\/div>  \n                                \n\n<\/div>\n        <\/div>\n    <\/div>\n    <div class=\"right_white_shape\">\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 180\">\n            <path class=\"cls-1\" d=\"M0,180H1000V.4S458.72-.5,279.85.4c-49,.25-68.29,7.31-161.7,105.9C94.46,131.3,49.5,174.7,0,180Z\" transform=\"translate(0 0)\"><\/path>\n        <\/svg>\n    <\/div>\n<\/section><div id=\"saz-block-id-BWgdY7qVLipl\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-yd1c1DqKqnTW\" class=\"saz-block saz-block-core-spacer saz-block-height-array\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-bxKUidWx30lK\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-xcooRyFlpbx5\" class=\"saz-block saz-block-core-quote\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>L\u2019intervento di Bonfiglioli Consulting ci ha aiutato a definire una nuova<strong> struttura organizzativa<\/strong> pronta per le sfide dei prossimi anni, accompagnandoci in ogni passo con professionalit\u00e0 e attenzione.<\/em><\/p><cite>Michele Storci, Amministratore Delegato<\/cite><\/blockquote>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-MC0RYMaodprE\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-iHHVkIWyLUbL\" class=\"saz-block saz-block-core-spacer saz-block-height-array\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-EPc4ecwumKJw\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-23972\" class=\"saz-block saz-block-core-image saz-block-align-center saz-block-id-array saz-block-width-array saz-block-height-array saz-block-sizeslug-large saz-block-linkdestination-none\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/05\/STORCI2.png\" alt=\"\" class=\"wp-image-23972 lazyload\" width=\"571\" height=\"384\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 571px; --smush-placeholder-aspect-ratio: 571\/384;\" \/><\/figure><\/div>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-tTHlEFZljPr2\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-ZgaziHRPgzlP\" class=\"saz-block saz-block-core-spacer saz-block-height-array\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-YZDm48khqV1Z\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-9lsfLGVDtG3A\" class=\"saz-block saz-block-core-quote\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>Abbiamo ora la consapevolezza di avere in Azienda processi snelli, robusti ed efficienti, sempre pi\u00f9 orientati alla soddisfazione del Cliente ed alla difesa della&nbsp; marginalit\u00e0.<\/em><\/p><cite>Simone Storci, Amministratore Delegato<\/cite><\/blockquote>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-ovhyi33BdV2N\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-Ynzhrry6UZk4\" class=\"saz-block saz-block-core-spacer saz-block-height-array\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-w99XKV2rKVpN\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-DXD4Um8MsRVc\" class=\"saz-block saz-block-core-heading saz-block-level-array\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<h3 class=\"wp-block-heading\"><span class=\"has-inline-color has-primary-color\"><strong>Scenario<\/strong><\/span><\/h3>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-GmX4B9ZYM3Ml\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-HcSnI0pmudzl\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Storci, nata ufficialmente nel 1991, ma con alle spalle oltre 60 anni di storia, si occupa della <strong>costruzione di macchine per produrre pasta<\/strong>.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-LzEqajMhWROp\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-mtOlNyPrhBZ7\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Nel 1995 inizia la partnership con Fava Spa, tra le eccellenze nel mondo della produzione di&nbsp;impianti per la pasta.\u200b<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-ZC2oBoPpJTj8\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-7ij5s2oeCu93\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Storci produce per Fava le presse per le linee industriali pi\u00f9 grandi del mondo, destinate alla&nbsp;produzione di pasta secca.\u200b<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-XddqgpN9eH8M\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-uikpKeYj6OzN\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Oggi il gruppo \u00e8 <strong>leader mondiale del settore<\/strong>, con circa il 40% del mercato.\u200b<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-XfRcfBpzSJoT\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-Q4pPljfZPjo7\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>A proprio marchio Storci realizza impianti destinati a tutte le altre produzioni: paste secche speciali,&nbsp;pasta fresca, piatti pronti, pasta&nbsp;instant, pasta senza glutine e couscous.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-uyiVeQJuI05l\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-y3eO6tiecnTb\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>La Direzione di Storci, ha <strong>deciso di aumentare la propria competitivit\u00e0<\/strong> migliorando le performance nei processi \u201ccore\u201d, ovvero preventivazione, progettazione, &nbsp;produzione e commissioning, grazie all<strong>\u2019applicazione dell\u2019<a href=\"https:\/\/www.bonfiglioliconsulting.com\/aree-di-intervento\/lean-thinking\/\">approccio LWC<\/a><\/strong><sup><a href=\"https:\/\/www.bonfiglioliconsulting.com\/aree-di-intervento\/lean-thinking\/\">\u00ae<\/a><\/sup>. &nbsp;<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-Z1mW1STB2j1P\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-KS0ds8Z097yx\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p><\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-Jg7RBtFwPoNZ\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-Zz3XyqYZMoEe\" class=\"saz-block saz-block-core-heading saz-block-level-array\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<h3 class=\"wp-block-heading\"><strong><span class=\"has-inline-color has-primary-color\">Ambiti di intervento<\/span><\/strong><\/h3>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-xypkAKBhOyQL\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-4NGZUaOSuUUx\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Il team di consulenza Bonfiglioli Consulting \u00e8 intervenuto:<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-pHDzIzATK04Y\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-7YMtkvcZ15z8\" class=\"saz-block saz-block-core-list\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<ul class=\"wp-block-list\"><li>Sui processi dell\u2019Area Tecnica,<ul><li>introducendo <strong>strumenti per la pianificazione delle risorse e la gestione della commessa<\/strong> cliente lungo tutto il loro sviluppo<\/li><\/ul><ul><li>agendo sul <strong>miglioramento del processo di pre-vendita<\/strong>, tramite la costruzione di un configuratore di prodotto tecnico\/commerciale, per la gestione robusta delle fasi di preventivazione,<\/li><\/ul><ul><li>lavorando sulla riduzione dei costi di prodotto (in termini di costi di acquisto per materiali e conto lavoro).<\/li><\/ul><\/li><\/ul>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-7qJtKK7xrBU8\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-wF3VyMOqC6Yw\" class=\"saz-block saz-block-core-list\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<ul class=\"wp-block-list\"><li>Sull\u2019organizzazione della fabbrica, attraverso:<ul><li>l\u2019<strong>applicazione del metodo 5S<\/strong><\/li><\/ul><ul><li>la <strong>riduzione delle attivit\u00e0 a non valore aggiunto <\/strong>(es. tempi di ricerca delle attrezzature, movimentazione dei materiali e rilavorazioni)<\/li><\/ul><ul><li>la <strong>gestione dei materiali<\/strong>, garantendo l\u2019arrivo dei componenti giusti nei momenti giusti e nella sequenza giusta<\/li><\/ul><\/li><\/ul>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-dOrwkYgLDagD\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-9efw6le4jaq7\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Al contempo \u00e8 stato <strong>rivisto l\u2019organigramma<\/strong>, in ottica di chiarezza sui rapporti gerarchici e definizione di responsabilit\u00e0 e mansioni.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-1kGALgJhF8zG\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-B0mmqoXmORvz\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>E\u2019 stato inoltre <strong>ottimizzato il processo di customer Service<\/strong>, con particolare attenzione al Commissioning, ovvero al delicato momento dell\u2019installazione e del collaudo degli impianti presso i Clienti di tutto il mondo.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-kgK4oj0KINwQ\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-fKNlq25nzOww\" class=\"saz-block saz-block-core-heading saz-block-level-array\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<h3 class=\"wp-block-heading\"><strong><span class=\"has-inline-color has-primary-color\">Risultati<\/span><\/strong><\/h3>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-O86EzzbwRCNe\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-XUhpEFrb0suO\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>L\u2019intervento ha portato ad uno snellimento della catena del Valore nella gestione dell\u2019intera commessa Storci (dall\u2019acquisizione dell\u2019ordine al commissioning presso il Cliente) basata su <strong>processi pi\u00f9 snelli, robusti e orientata ai risultati.<\/strong><\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-AqAvMzcCo81r\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-YCH4of7e0g8h\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Si \u00e8 ottenuta una maggiore consapevolezza nella Struttura dei rapporti gerarchici e delle proprie mansioni e responsabilit\u00e0.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-ggMvmrCrZJR9\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-SQYCWUPlHkJ8\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Inoltre, l\u2019attivazione del Configuratore di prodotto ha reso <strong>pi\u00f9 precisa e performante l\u2019attivit\u00e0 di preventivazione<\/strong> riducendo notevolmente il Lead Time di generazione dell\u2019Offerta e la precisione sui margini attesi.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-ND5hPpxQaLeb\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-bdSr5tbPYDZM\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>In termini numerici si contano:<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-m6W6Yb6utRx2\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-08iRcuzBhTPk\" class=\"saz-block saz-block-core-list\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<ul class=\"wp-block-list\"><li>Riduzione del costo di acquisto per materiali (componenti e conto lavoro) dell\u20198%<\/li><li>Aumento della produttivit\u00e0 in Ufficio Tecnico del 12%\u200b<\/li><li>Aumento della produttivit\u00e0 al Montaggio del 18%\u200b<\/li><li>Attivazione Configuratore prodotto per il 90% delle macchine standard&nbsp;<\/li><\/ul>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-2FW8tVa8su3Q\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-w6eLI8mFF2C5\" class=\"saz-block saz-block-core-spacer saz-block-height-array\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-fJVfMt4TMDfi\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-qbDdZU3P3FAW\" class=\"saz-block saz-block-core-spacer saz-block-height-array\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-8nqlK1lroRl7\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-block_60950d0b209bb\" class=\"saz-block saz-block-acf-onda \" style=\"background-color: #ffffff\">\n    <div class=\"container-fluid\">\n                    <div class=\"row\">\n                <div class=\"col-lg-9 pl-0\">\n                    <svg id=\"onda-blocchi\" class=\"reverse\" data-name=\"onda\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 180\"><path class=\"cls-1\" d=\"M0,180H1000V.4S458.72-.5,279.85.4c-49,.25-68.29,7.31-161.7,105.9C94.46,131.3,49.5,174.7,0,180Z\" transform=\"translate(0 0)\" style=\"fill: #e3e9ed\"\/><\/svg>\n                <\/div>\n            <\/div>\n            <\/div>\n<\/div><div id=\"saz-block-id-UFTqgxnzvC4C\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div>    <div id=\"number-block_60950c36209b9\" class=\"saz-block saz-block-acf-number py-5\" style=\"background-color:#e3e9ed\">\n        <div class=\"container\">\n                                <div class=\"row\">\n                        <div class=\"col text-center\">\n                            <h3 class=\"font-weight-bold text-uppercase mb-4 text-gray\">Obiettivi raggiunti<\/h3>\n                        <\/div>\n                    <\/div>\n                        <div class=\"row\">\n                                    <div class=\"col-12 col-md text-center\">\n                         <div class=\"block\"><div class=\"hovicon effect-1 sub-a\"><div class=\"font-weight-light text-primary\"><span>+18%<\/span><\/div><\/div><\/div><p class=\"mb-4 mt-0 my-lg-0 text-gray\">PRODUTTIVITA&#8217; AL MONTAGGIOI<\/p>                    <\/div>\n                                    <div class=\"col-12 col-md text-center\">\n                         <div class=\"block\"><div class=\"hovicon effect-1 sub-a\"><div class=\"font-weight-light text-primary\"><span>-8%<\/span><\/div><\/div><\/div><p class=\"mb-4 mt-0 my-lg-0 text-gray\">COSTO ACQUISTO MATERIALI<\/p>                    <\/div>\n                                    <div class=\"col-12 col-md text-center\">\n                         <div class=\"block\"><div class=\"hovicon effect-1 sub-a\"><div class=\"font-weight-light text-primary\"><span>+12%<\/span><\/div><\/div><\/div><p class=\"mb-4 mt-0 my-lg-0 text-gray\">AUMENTO PRODUTTIVITA&#8217;<\/p>                    <\/div>\n                            <\/div>\n        <\/div>\n    <\/div>\n\n  ","protected":false},"excerpt":{"rendered":null,"protected":false},"author":73,"featured_media":23976,"parent":0,"menu_order":86,"comment_status":"closed","ping_status":"closed","template":"template-wide-blocchi.php","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"class_list":["post-23967","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Storci SpA: efficienza e qualit\u00e0 | Bonfiglioli Consulting<\/title>\n<meta name=\"description\" content=\"Storci Spa: Scopri come la compagnia Storci Spa ha migliorato i processi produttivi in azienda con approcci innovativi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonfiglioliconsulting.com\/en\/storci-spa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Storci SpA: efficienza e qualit\u00e0 | Bonfiglioli Consulting\" \/>\n<meta property=\"og:description\" content=\"Storci Spa: Scopri come la compagnia Storci Spa ha migliorato i processi produttivi in azienda con approcci innovativi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonfiglioliconsulting.com\/en\/storci-spa\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonfiglioli Consulting\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-28T13:43:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/05\/BANNER-STORCI.png\" \/>\n\t<meta property=\"og:image:width\" content=\"295\" \/>\n\t<meta property=\"og:image:height\" content=\"177\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/storci-spa\\\/\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/storci-spa\\\/\",\"name\":\"Storci SpA: efficienza e qualit\u00e0 | Bonfiglioli Consulting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/storci-spa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/storci-spa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/BANNER-STORCI.png\",\"datePublished\":\"2021-05-07T09:49:16+00:00\",\"dateModified\":\"2025-08-28T13:43:37+00:00\",\"description\":\"Storci Spa: Scopri come la compagnia Storci Spa ha migliorato i processi produttivi in azienda con approcci innovativi.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/storci-spa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/storci-spa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/BANNER-STORCI.png\",\"contentUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/BANNER-STORCI.png\",\"width\":295,\"height\":177},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/\",\"name\":\"Bonfiglioli Consulting\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Storci SpA: efficiency and quality | Bonfiglioli Consulting","description":"Storci Spa: Learn how the company Storci Spa has improved production processes in the company with innovative approaches.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonfiglioliconsulting.com\/en\/storci-spa\/","og_locale":"en_US","og_type":"article","og_title":"Storci SpA: efficienza e qualit\u00e0 | Bonfiglioli Consulting","og_description":"Storci Spa: Scopri come la compagnia Storci Spa ha migliorato i processi produttivi in azienda con approcci innovativi.","og_url":"https:\/\/www.bonfiglioliconsulting.com\/en\/storci-spa\/","og_site_name":"Bonfiglioli Consulting","article_modified_time":"2025-08-28T13:43:37+00:00","og_image":[{"width":295,"height":177,"url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/05\/BANNER-STORCI.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/storci-spa\/","url":"https:\/\/www.bonfiglioliconsulting.com\/it\/storci-spa\/","name":"Storci SpA: efficiency and quality | Bonfiglioli Consulting","isPartOf":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/storci-spa\/#primaryimage"},"image":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/storci-spa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/05\/BANNER-STORCI.png","datePublished":"2021-05-07T09:49:16+00:00","dateModified":"2025-08-28T13:43:37+00:00","description":"Storci Spa: Learn how the company Storci Spa has improved production processes in the company with innovative approaches.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bonfiglioliconsulting.com\/it\/storci-spa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/storci-spa\/#primaryimage","url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/05\/BANNER-STORCI.png","contentUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/05\/BANNER-STORCI.png","width":295,"height":177},{"@type":"WebSite","@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website","url":"https:\/\/www.bonfiglioliconsulting.com\/it\/","name":"Bonfiglioli Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonfiglioliconsulting.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"atf_populated":false,"_links":{"self":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/pages\/23967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/comments?post=23967"}],"version-history":[{"count":14,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/pages\/23967\/revisions"}],"predecessor-version":[{"id":64014,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/pages\/23967\/revisions\/64014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/media\/23976"}],"wp:attachment":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/media?parent=23967"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/tags?post=23967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}