{"id":22808,"date":"2020-04-16T11:36:00","date_gmt":"2020-04-16T09:36:00","guid":{"rendered":"https:\/\/www.bcsoa.it\/?page_id=22808"},"modified":"2025-06-16T16:46:31","modified_gmt":"2025-06-16T14:46:31","slug":"the-digitization-of-the-line-slaving-process-in-baltur","status":"publish","type":"page","link":"https:\/\/www.bonfiglioliconsulting.com\/en\/la-digitalizzazione-del-processo-di-asservimento-linea-in-baltur\/","title":{"rendered":"The digitization of the line-slaving process in Baltur"},"content":{"rendered":"<div id=\"saz-block-block_60795438b961a\" class=\"d-none saz-block saz-block-acf-hero-servizi  bg-light bg-hero-servizi-eventi hero_overlay_parent vv lazyload\"\n     style=\"background:inherit; background-size:cover;\" data-bg=\"url(https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/04\/hero-francesco-sena3.png) center top no-repeat transparent\">\n    <div class=\"hero_overlay\"><\/div>\n    <div class=\"container hero_content\">\n        <div class=\"row align-items-end\">\n            <div class=\"col-12\">\n                 \n                    <div class=\"mt-3 mb-2 text-dark\"><div class=\"breadcrumbs\"><span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" title=\"Vai a Bonfiglioli Consulting.\" href=\"https:\/\/www.bonfiglioliconsulting.com\/en\" class=\"home\"><span property=\"name\">Home<\/span><\/a><meta property=\"position\" content=\"1\"><\/span><\/div><script type=\"application\/ld+json\">{\"@context\":\"http:\/\/schema.org\",\"@type\":\"BreadcrumbList\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@id\":\"https:\/\/www.bonfiglioliconsulting.com\/en\",\"name\":\"Bonfiglioli Consulting\"}}]}<\/script><\/div>\n                                \n                                    <h1 class=\"has-huge-font-size font-weight-bold mb-0 text-dark\">La digitalizzazione del processo di asservimento linea in Baltur<\/h1>\n                                                    <h2 class=\"has-medium-font-size my-3 font-weight-normal text-dark\">Intervista a Francesco Sena, Direttore Operations<\/h2>\n                                <div class=\"mb-5 pb-4 pb-md-5\"><\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n    <svg class=\"onda-destra\" id=\"onda\" data-name=\"onda\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 180\"><path class=\"cls-1\" d=\"M0,180H1000V.4S458.72-.5,279.85.4c-49,.25-68.29,7.31-161.7,105.9C94.46,131.3,49.5,174.7,0,180Z\" transform=\"translate(0 0)\" style=\"fill: #ffffff\"\/><\/svg>\n<\/div>\n\n\n<section class=\"n_archive_hero lazyload\" style=\"background-image:inherit;\" data-bg-image=\"url(https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/04\/hero-francesco-sena3.png)\"> \n    <div class=\"container h-100 position-relative\">\n        <div class=\"d-flex items-center h-100\">\n            <div class=\"n_archive_hero_content align-self-end text-white\">\n                <div class=\"text-white\">\n                <div class=\"breadcrumbs\">\n                 \n                    <div class=\"mt-3 mb-2 text-dark\"><div class=\"breadcrumbs\"><span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" title=\"Vai a Bonfiglioli Consulting.\" href=\"https:\/\/www.bonfiglioliconsulting.com\/en\" class=\"home\"><span property=\"name\">Home<\/span><\/a><meta property=\"position\" content=\"1\"><\/span><\/div><script type=\"application\/ld+json\">{\"@context\":\"http:\/\/schema.org\",\"@type\":\"BreadcrumbList\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@id\":\"https:\/\/www.bonfiglioliconsulting.com\/en\",\"name\":\"Bonfiglioli Consulting\"}}]}<\/script><\/div>\n                                <\/div>\n                <\/div>\n                \n                \n                \n                                      <h1 class=\"text-white text-dark\">La digitalizzazione del processo di asservimento linea in Baltur<\/h1>\n                                \n                                    <div class=\"n_archive_desc\"> \n                     <p class=\"text-dark\">\n                       Intervista a Francesco Sena, Direttore Operations                     <\/p>\n                    <\/div>  \n                                \n\n<\/div>\n        <\/div>\n    <\/div>\n    <div class=\"right_white_shape\">\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 180\">\n            <path class=\"cls-1\" d=\"M0,180H1000V.4S458.72-.5,279.85.4c-49,.25-68.29,7.31-161.7,105.9C94.46,131.3,49.5,174.7,0,180Z\" transform=\"translate(0 0)\"><\/path>\n        <\/svg>\n    <\/div>\n<\/section><div id=\"saz-block-id-aEcBn3t4JEIp\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-eHuZwJg18Qjp\" class=\"saz-block saz-block-core-spacer saz-block-height-array\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-Ee5IXyUS3PjU\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-fPhV9MybhyjS\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Dal 1950, Baltur \u00e8 un marchio d\u2019eccellenza nelle tecnologie della combustione. In 70 anni di attivit\u00e0, ha saputo raggiungere l\u2019equilibrio perfetto tra performance e risparmio, comfort e sostenibilit\u00e0. Grazie a investimenti continui in ricerca e innovazione, oggi \u00e8 in grado di soddisfare sia l\u2019industria sia il privato attraverso una gamma completa di bruciatori, con elevatissimi rapporti di modulazione e basse emissioni inquinanti, prodotti per il comfort residenziale e la climatizzazione. <\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-2xgyILahGjaA\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-CvTi4ZvvOitZ\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Baltur opera secondo i principi di Lean Management e Industry 4.0, ce ne ha parlato <strong>Francesco Sena, Direttore Operations.<\/strong>\u201c\u00c8 gi\u00e0 da qualche anno che, incuriositi da questo fermento intorno alle tecnologie della nuova rivoluzione industriale, abbiamo iniziato a documentarci e a confrontarci con vari esperti, in particolare con Bonfiglioli Consulting, nostro partner sul miglioramento continuo, per capire quali tecnologie digitali applicare a quali processi, consapevoli in ogni caso che si tratta di una nuova logica che riguarda trasversalmente tutta l\u2019azienda.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-LWuyoNhoN10I\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-2jwkGCjgaQ3Q\" class=\"saz-block saz-block-core-quote\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Dopo un\u2019iniziale attivit\u00e0 di scouting che ha individuato 3 aree di intervento, abbiamo deciso di concentrarci su una di esse, la logistica, potenziandola con l\u2019aiuto delle tecnologie digitali.<\/p><\/blockquote>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-MW0W0BdRAwpB\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-aTsDQVizNV0k\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p><\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-33CdVYTyge6t\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-HTobCjmEXOz7\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Ogni giorno Baltur produce una media di 160 bruciatori, ciascuno dei quali \u00e8 composto in media da 300 componenti, che vuol dire ben <strong>48.000 componenti da prelevare, assemblare e tenere sotto controllo quotidianamente<\/strong>: alcuni ad esempio possono sembrare identici pur non essendolo, avendo all\u2019interno schede elettroniche oppure componenti diversi che ne mutano la potenza e il loro utilizzo. Questi componenti ritenuti critici generano circa 11.000 articoli da controllare e verificare con la massima attenzione ogni giorno. Anche se la percentuale di errori \u00e8 abbastanza contenuta, tra lo 0,1% e lo 0,15%, <strong>negli ultimi 9 mesi abbiamo misurato e intercettato diversi errori,<\/strong> sia nel nostro processo interno, che nel processo esterno. <strong>I costi derivanti da questi fattori (cosiddetti costi della non qualit\u00e0) si sono attestati, solo nel primo anno, a 90.000 euro<\/strong>, e sono fermamente convinto che questo sia solo l\u2019inizio. <\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-nQDhLCOe4I60\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-22836\" class=\"saz-block saz-block-core-image saz-block-id-array saz-block-sizeslug-large saz-block-linkdestination-none\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"597\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/04\/testimonianza-baltur-hero-1-1024x597.png\" alt=\"\" class=\"wp-image-22836 lazyload\" data-srcset=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/04\/testimonianza-baltur-hero-1-1024x597.png 1024w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/04\/testimonianza-baltur-hero-1-750x437.png 750w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/04\/testimonianza-baltur-hero-1-600x350.png 600w, https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/04\/testimonianza-baltur-hero-1.png 1118w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/597;\" \/><\/figure>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-26nMjb9J8zTo\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-YwPjRLrJP9D3\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p><strong>Il progetto pilota si \u00e8 dunque focalizzato sul processo di asservimento linea<\/strong>, ossia su quelle operazioni che i magazzinieri compiono ogni ora, per disporre sui carrelli tutti i componenti per assemblare i nostri bruciatori. Questi vengono portati in apposite aree, che si trovano in prossimit\u00e0 delle linee di assemblaggio.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-icLW4hK0b8Tu\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-lIU2YQFUk0WK\" class=\"saz-block saz-block-core-quote\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><br>Obiettivo: avere sulla linea solo i componenti giusti al momento giusto. <\/p><\/blockquote>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-QGmrus3fbC3r\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-fQ9yoQYzTJFh\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p><\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-J1qV2oZhD1Vr\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-63MV1M2EFLDF\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>L\u2019intero processo attualmente \u00e8 supportato da un <strong>robusto sistema informativo<\/strong>. Il magazziniere oggi, preleva i componenti utilizzando un sistema misto, composto da carta e lettore bar code. La carta \u00e8 comoda perch\u00e9 leggera, ma non \u00e8 aggiornata, nel senso che anche nel caso in cui i documenti di prelievo vengano stampati la mattina stessa, pu\u00f2 accadere che cambino durante il giorno (ad esempio alcuni componenti possono arrivare in ritardo rispetto alla schedulazione di produzione, perch\u00e9 sottoposti a verifica di qualit\u00e0). Pu\u00f2 accadere quindi che l\u2019operatore si trovi di fronte a una situazione di non allineamento fra la carta e quello che in realt\u00e0 pu\u00f2 prelevare. <\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-X5dwJL9FbFa2\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-mdJOVTCxSqzt\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p><strong>Il progetto di digitalizzazione della linea, che abbiamo denominato SmartKart, prevede l\u2019inserimento a bordo di specifici carrelli di un tablet interfacciato in tempo reale al gestionale aziendale.<\/strong> In tal modo, quando l\u2019operatore di magazzino, da noi denominato \u2018kittatore\u2019, preparer\u00e0 i componenti della distinta base di assemblaggio del bruciatore, oltre alla verifica visiva e a quella con bar code, avr\u00e0 con il tablet la possibilit\u00e0 di vedere immagini esclusive e informazioni specifiche del componente da prelevare da confrontare poi con il suo terminale radio, per avere la matematica certezza di aver prelevato quello giusto.Tutto questo sistema sar\u00e0 poi collegato al processo di fabbricazione in linea. Oggi i conduttori della linea non hanno modo di monitorare in anticipo l\u2019approntamento dei carrelli: ecco perch\u00e9 abbiamo gi\u00e0 previsto <strong>un secondo step che riguarda la creazione di una struttura informativa interna dove ogni carrello avr\u00e0 un orario di partenza e un orario di arrivo<\/strong> (molto simile ai tabelloni degli aeroporti o delle stazioni ferroviarie). L\u2019area carrelli verr\u00e0 quindi dotata di un monitor fisso dove verr\u00e0 segnalato quale SmartKart prelevare da portare a bordo linea, oppure quale Smarkart \u00e8 libero da utilizzare. <\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-yK9sK6jIy8e5\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-LDhnsZxmRbFj\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p><strong>La terza fase del progetto poi prevede che anche l\u2019operatore che assembla il componente avr\u00e0 a bordo della sua postazione di lavoro un ulteriore tablet che gli dir\u00e0 esattamente il codice componente da prelevare e gliene mostrer\u00e0 un\u2019immagine per garantire che sia quello giusto<\/strong>.<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-suYu1e7aEhmV\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-BfNxxehNclIg\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p>Cosa comporta tutto ci\u00f2? Comporta che nel caso in cui un cliente segnali un\u2019anomalia o un cattivo funzionamento di un bruciatore, Baltur avr\u00e0 la mappatura di tutto il processo di logistica e fabbricazione che gli permetter\u00e0 di intraprendere tempestivamente le pi\u00f9 appropriate azioni correttive. In tale ottica, le tecnologie di Industry 4.0 ritengo siano un valido alleato per semplificare e continuare il processo di \u2018Miglioramento Continuo\u2019 e garantire sempre pi\u00f9 al mercato un prodotto d\u2019eccellenza che ci distingua tra i migliori player del settore.\u201d<\/p>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-CS1RPe7HwiCA\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-NRJf3PAZ8i2H\" class=\"saz-block saz-block-core-heading saz-block-level-array\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<h3 class=\"wp-block-heading\"><strong>Baltur, primo progetto 4.0 &#8211; Il video<\/strong><\/h3>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-5uWXAuICjJfb\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-xZpL0EZhrbj0\" class=\"saz-block saz-block-core-shortcode\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\"><div class=\"video embed-responsive embed-responsive-16by9\"><iframe width=\"940\" height=\"529\" data-src=\"https:\/\/player.vimeo.com\/video\/218909557?title=0&byline=0&portrait=0&controls=1&muted=0&autoplay=0&loop=0\" frameborder=\"0\" webkitallowfullscreen mozallowfullscreen allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/div>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-iUOxbOCow1b5\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-r9QKwGI6CMmn\" class=\"saz-block saz-block-core-spacer saz-block-height-array\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-bZAY8r6Rgg8H\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-RfwUqbGklDgr\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p><\/p>\n<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":null,"protected":false},"author":73,"featured_media":24047,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-wide-blocchi.php","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"class_list":["post-22808","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La digitalizzazione del processo di asservimento linea in Baltur<\/title>\n<meta name=\"description\" content=\"Digitalizzazione in Baltur: Approfondisci come Baltur ha digitalizzato il processo di asservimento linea in azienda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonfiglioliconsulting.com\/en\/the-digitization-of-the-line-slaving-process-in-baltur\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La digitalizzazione del processo di asservimento linea in Baltur\" \/>\n<meta property=\"og:description\" content=\"Digitalizzazione in Baltur: Approfondisci come Baltur ha digitalizzato il processo di asservimento linea in azienda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonfiglioliconsulting.com\/en\/the-digitization-of-the-line-slaving-process-in-baltur\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonfiglioli Consulting\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-16T14:46:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/05\/testimonianza-baltur-spa-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"295\" \/>\n\t<meta property=\"og:image:height\" content=\"177\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/la-digitalizzazione-del-processo-di-asservimento-linea-in-baltur\\\/\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/la-digitalizzazione-del-processo-di-asservimento-linea-in-baltur\\\/\",\"name\":\"La digitalizzazione del processo di asservimento linea in Baltur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/la-digitalizzazione-del-processo-di-asservimento-linea-in-baltur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/la-digitalizzazione-del-processo-di-asservimento-linea-in-baltur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/testimonianza-baltur-spa-2.jpg\",\"datePublished\":\"2020-04-16T09:36:00+00:00\",\"dateModified\":\"2025-06-16T14:46:31+00:00\",\"description\":\"Digitalizzazione in Baltur: Approfondisci come Baltur ha digitalizzato il processo di asservimento linea in azienda.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/la-digitalizzazione-del-processo-di-asservimento-linea-in-baltur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/la-digitalizzazione-del-processo-di-asservimento-linea-in-baltur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/testimonianza-baltur-spa-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/testimonianza-baltur-spa-2.jpg\",\"width\":295,\"height\":177},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/\",\"name\":\"Bonfiglioli Consulting\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The digitization of the line-slaving process in Baltur","description":"Digitization in Baltur: Learn more about how Baltur has digitized the line-slaving process in the company.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonfiglioliconsulting.com\/en\/the-digitization-of-the-line-slaving-process-in-baltur\/","og_locale":"en_US","og_type":"article","og_title":"La digitalizzazione del processo di asservimento linea in Baltur","og_description":"Digitalizzazione in Baltur: Approfondisci come Baltur ha digitalizzato il processo di asservimento linea in azienda.","og_url":"https:\/\/www.bonfiglioliconsulting.com\/en\/the-digitization-of-the-line-slaving-process-in-baltur\/","og_site_name":"Bonfiglioli Consulting","article_modified_time":"2025-06-16T14:46:31+00:00","og_image":[{"width":295,"height":177,"url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/05\/testimonianza-baltur-spa-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bonfiglioliconsulting.com\/la-digitalizzazione-del-processo-di-asservimento-linea-in-baltur\/","url":"https:\/\/www.bonfiglioliconsulting.com\/la-digitalizzazione-del-processo-di-asservimento-linea-in-baltur\/","name":"The digitization of the line-slaving process in Baltur","isPartOf":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/la-digitalizzazione-del-processo-di-asservimento-linea-in-baltur\/#primaryimage"},"image":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/la-digitalizzazione-del-processo-di-asservimento-linea-in-baltur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/05\/testimonianza-baltur-spa-2.jpg","datePublished":"2020-04-16T09:36:00+00:00","dateModified":"2025-06-16T14:46:31+00:00","description":"Digitization in Baltur: Learn more about how Baltur has digitized the line-slaving process in the company.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bonfiglioliconsulting.com\/la-digitalizzazione-del-processo-di-asservimento-linea-in-baltur\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bonfiglioliconsulting.com\/la-digitalizzazione-del-processo-di-asservimento-linea-in-baltur\/#primaryimage","url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/05\/testimonianza-baltur-spa-2.jpg","contentUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2021\/05\/testimonianza-baltur-spa-2.jpg","width":295,"height":177},{"@type":"WebSite","@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website","url":"https:\/\/www.bonfiglioliconsulting.com\/it\/","name":"Bonfiglioli Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonfiglioliconsulting.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"atf_populated":false,"_links":{"self":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/pages\/22808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/comments?post=22808"}],"version-history":[{"count":20,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/pages\/22808\/revisions"}],"predecessor-version":[{"id":64018,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/pages\/22808\/revisions\/64018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/media\/24047"}],"wp:attachment":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/media?parent=22808"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/tags?post=22808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}