{"id":51843,"date":"2023-12-01T12:54:45","date_gmt":"2023-12-01T11:54:45","guid":{"rendered":"https:\/\/www.bcsoa.it\/?post_type=course&#038;p=51843"},"modified":"2025-01-07T18:01:09","modified_gmt":"2025-01-07T17:01:09","slug":"qa-how-to-become-lean-expert","status":"publish","type":"course","link":"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/qa-come-diventare-lean-expert\/","title":{"rendered":"Q&amp;A | How to become a Lean Expert?"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":null,"protected":false},"featured_media":51844,"menu_order":29898,"template":"","tipologia":[89],"content_type":[],"class_list":["post-51843","course","type-course","status-publish","has-post-thumbnail","hentry","tipologia-appuntamenti"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come Diventare Lean Expert? Q&amp;A - Bonfiglioli Consulting<\/title>\n<meta name=\"description\" content=\"Come diventare un Lean Expert? Scopri il nostro programma formativo per trasformare la conoscenza in competenza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/qa-how-to-become-lean-expert\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come Diventare Lean Expert? Q&amp;A - Bonfiglioli Consulting\" \/>\n<meta property=\"og:description\" content=\"Come diventare un Lean Expert? Scopri il nostro programma formativo per trasformare la conoscenza in competenza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/qa-how-to-become-lean-expert\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonfiglioli Consulting\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-07T17:01:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/12\/Banner-Lean-Expert.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1425\" \/>\n\t<meta property=\"og:image:height\" content=\"805\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/qa-come-diventare-lean-expert\\\/\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/qa-come-diventare-lean-expert\\\/\",\"name\":\"Come Diventare Lean Expert? Q&A - Bonfiglioli Consulting\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/qa-come-diventare-lean-expert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/qa-come-diventare-lean-expert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Banner-Lean-Expert.png\",\"datePublished\":\"2023-12-01T11:54:45+00:00\",\"dateModified\":\"2025-01-07T17:01:09+00:00\",\"description\":\"Come diventare un Lean Expert? Scopri il nostro programma formativo per trasformare la conoscenza in competenza.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/qa-come-diventare-lean-expert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/qa-come-diventare-lean-expert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Banner-Lean-Expert.png\",\"contentUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Banner-Lean-Expert.png\",\"width\":1425,\"height\":805,\"caption\":\"Banner Lean Expert \u2013 Bonfiglioli Consulting\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/\",\"name\":\"Bonfiglioli Consulting\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"How to Become a Lean Expert? Q&amp;A - Bonfiglioli Consulting","description":"How to become a Lean Expert? Learn about our training program to turn knowledge into expertise.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/qa-how-to-become-lean-expert\/","og_locale":"en_US","og_type":"article","og_title":"Come Diventare Lean Expert? Q&A - Bonfiglioli Consulting","og_description":"Come diventare un Lean Expert? Scopri il nostro programma formativo per trasformare la conoscenza in competenza.","og_url":"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/qa-how-to-become-lean-expert\/","og_site_name":"Bonfiglioli Consulting","article_modified_time":"2025-01-07T17:01:09+00:00","og_image":[{"width":1425,"height":805,"url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/12\/Banner-Lean-Expert.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/qa-come-diventare-lean-expert\/","url":"https:\/\/www.bonfiglioliconsulting.com\/events\/qa-come-diventare-lean-expert\/","name":"How to Become a Lean Expert? Q&amp;A - Bonfiglioli Consulting","isPartOf":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/qa-come-diventare-lean-expert\/#primaryimage"},"image":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/qa-come-diventare-lean-expert\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/12\/Banner-Lean-Expert.png","datePublished":"2023-12-01T11:54:45+00:00","dateModified":"2025-01-07T17:01:09+00:00","description":"How to become a Lean Expert? Learn about our training program to turn knowledge into expertise.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bonfiglioliconsulting.com\/events\/qa-come-diventare-lean-expert\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/qa-come-diventare-lean-expert\/#primaryimage","url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/12\/Banner-Lean-Expert.png","contentUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/12\/Banner-Lean-Expert.png","width":1425,"height":805,"caption":"Banner Lean Expert \u2013 Bonfiglioli Consulting"},{"@type":"WebSite","@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website","url":"https:\/\/www.bonfiglioliconsulting.com\/it\/","name":"Bonfiglioli Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonfiglioliconsulting.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"atf_populated":false,"_links":{"self":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/course\/51843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/types\/course"}],"version-history":[{"count":11,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/course\/51843\/revisions"}],"predecessor-version":[{"id":52306,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/course\/51843\/revisions\/52306"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/media\/51844"}],"wp:attachment":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/media?parent=51843"}],"wp:term":[{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/tipologia?post=51843"},{"taxonomy":"content_type","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/content_type?post=51843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}