{"id":44449,"date":"2023-05-22T13:31:15","date_gmt":"2023-05-22T11:31:15","guid":{"rendered":"https:\/\/www.bcsoa.it\/?post_type=course&#038;p=44449"},"modified":"2025-11-13T07:19:13","modified_gmt":"2025-11-13T06:19:13","slug":"digital-talk-why-companies-should-implement-salesoperations-planning-process","status":"publish","type":"course","link":"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/digital-talk-perche-le-aziende-dovrebbero-implementare-il-processo-di-salesoperations-planning\/","title":{"rendered":"Digital Talk | Why should companies implement Sales&amp;Operations Planning process?"},"content":{"rendered":"<div id=\"saz-block-block_cfe1bd4eb93d41dbca1e500579b1f381\" class=\"saz-block saz-block-acf-onda\" style=\"background-color: #ffffff\">\n    <div class=\"container-fluid\">\n                    <div class=\"row\">\n                <div class=\"col-lg-9 pl-0\">\n                    <svg id=\"onda-blocchi\" class=\"reverse\" data-name=\"onda\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 180\"><path class=\"cls-1\" d=\"M0,180H1000V.4S458.72-.5,279.85.4c-49,.25-68.29,7.31-161.7,105.9C94.46,131.3,49.5,174.7,0,180Z\" transform=\"translate(0 0)\" style=\"fill: #32468c\"\/><\/svg>\n                <\/div>\n            <\/div>\n            <\/div>\n<\/div><div id=\"saz-block-id-8509QfiV6QKg\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-7lWlnAm5mjFS\" class=\"saz-block saz-block-core-heading saz-block-style-array saz-block-backgroundcolor-primary saz-block-textcolor-white saz-block-classname-wp-elements-1\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<h2 class=\"wp-block-heading has-white-color has-primary-background-color has-text-color has-background has-link-color wp-elements-1\"><strong>Speaker<\/strong><\/h2>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-cwijFB9gwiTt\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-hQBIhoW13naF\" class=\"saz-block saz-block-core-columns saz-block-verticalalignment-center saz-block-align-wide saz-block-classname-pt-4-pb-5-wp-elements-2 saz-block-style-array saz-block-backgroundcolor-primary saz-block-textcolor-white\"><div class=\"container\"><div class=\"row\">\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center pt-4 pb-5 has-white-color has-primary-background-color has-text-color has-background has-link-color wp-elements-2 is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><div id=\"saz-block-id-32148\" class=\"saz-block saz-block-core-image saz-block-id-array saz-block-width-176px saz-block-sizeslug-full saz-block-linkdestination-none saz-block-classname-is-style-rounded\">\n<figure class=\"wp-block-image size-full is-resized is-style-rounded\"><img decoding=\"async\" width=\"265\" height=\"265\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2022\/04\/BRANDALESI-1.jpg\" alt=\"\" class=\"wp-image-32148 lazyload\" style=\"--smush-placeholder-width: 265px; --smush-placeholder-aspect-ratio: 265\/265;width:176px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:70%\"><div id=\"saz-block-id-mQa7cTBtmA6q\" class=\"saz-block saz-block-core-heading saz-block-level-array saz-block-style-array saz-block-textcolor-white saz-block-fontsize-medium saz-block-classname-wp-elements-3\">\n<h3 class=\"wp-block-heading has-white-color has-text-color has-link-color has-medium-font-size wp-elements-3\"><strong>MARCO BRANDALESI<\/strong> | BONFIGLIOLI CONSULTING<\/h3>\n<\/div>\n\n<div id=\"saz-block-id-zgYZZx5QjwxB\" class=\"saz-block saz-block-core-paragraph saz-block-style-array saz-block-textcolor-white saz-block-fontsize-medium saz-block-classname-wp-elements-4\">\n<p class=\"has-white-color has-text-color has-link-color has-medium-font-size wp-elements-4 wp-block-paragraph\">Principal Supply Chain, Manufacturing and Operational<br>Excellence.&nbsp;<\/p>\n<\/div>\n\n<div id=\"saz-block-id-ycd6FzJyqhA1\" class=\"saz-block saz-block-core-paragraph\">\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.linkedin.com\/in\/marco-brandalesi-a0b8a556\/\">LinkedIn<\/a><\/p>\n<\/div><\/div>\n<\/div>\n<\/div><\/div><\/div><div id=\"saz-block-id-Rl5UYNQAReiN\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-7bQX0ZMFnuSd\" class=\"saz-block saz-block-core-paragraph\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":null,"protected":false},"featured_media":65268,"menu_order":10492,"template":"","tipologia":[50],"content_type":[155],"class_list":["post-44449","course","type-course","status-publish","has-post-thumbnail","hentry","tipologia-workshop-digital-talk","content_type-evento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Perch\u00e9 il processo di Sales&amp;Operations Planning?<\/title>\n<meta name=\"description\" content=\"Sales Operations Planning \u2013 Scopri perch\u00e9 implementare un processo di Sales Operations Planning pu\u00f2 migliorare la pianificazione aziendale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/digital-talk-why-companies-should-implement-salesoperations-planning-process\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perch\u00e9 il processo di Sales&amp;Operations Planning?\" \/>\n<meta property=\"og:description\" content=\"Sales Operations Planning \u2013 Scopri perch\u00e9 implementare un processo di Sales Operations Planning pu\u00f2 migliorare la pianificazione aziendale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/digital-talk-why-companies-should-implement-salesoperations-planning-process\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonfiglioli Consulting\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T06:19:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/05\/ImmagineBANNER-SOP_GIUGNO2025-1024x578.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"578\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/digital-talk-perche-le-aziende-dovrebbero-implementare-il-processo-di-salesoperations-planning\\\/\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/digital-talk-perche-le-aziende-dovrebbero-implementare-il-processo-di-salesoperations-planning\\\/\",\"name\":\"Perch\u00e9 il processo di Sales&Operations Planning?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/digital-talk-perche-le-aziende-dovrebbero-implementare-il-processo-di-salesoperations-planning\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/digital-talk-perche-le-aziende-dovrebbero-implementare-il-processo-di-salesoperations-planning\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/ImmagineBANNER-SOP_GIUGNO2025.png\",\"datePublished\":\"2023-05-22T11:31:15+00:00\",\"dateModified\":\"2025-11-13T06:19:13+00:00\",\"description\":\"Sales Operations Planning \u2013 Scopri perch\u00e9 implementare un processo di Sales Operations Planning pu\u00f2 migliorare la pianificazione aziendale.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/digital-talk-perche-le-aziende-dovrebbero-implementare-il-processo-di-salesoperations-planning\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/digital-talk-perche-le-aziende-dovrebbero-implementare-il-processo-di-salesoperations-planning\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/ImmagineBANNER-SOP_GIUGNO2025.png\",\"contentUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/ImmagineBANNER-SOP_GIUGNO2025.png\",\"width\":1994,\"height\":1125,\"caption\":\"In un ufficio ben illuminato, professionisti in abiti da lavoro esaminano un grafico. L'immagine presenta il testo: \\\"26 Giugno 2025 Digital Talk in Diretta Streaming\\\", che sottolinea l'importanza della pianificazione delle vendite e delle operazioni per le aziende che navigano nel panorama digitale in continua evoluzione.\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/\",\"name\":\"Bonfiglioli Consulting\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Why the Sales&amp;Operations Planning process?","description":"Sales Operations Planning - Learn why implementing a Sales Operations Planning process can improve business planning.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/digital-talk-why-companies-should-implement-salesoperations-planning-process\/","og_locale":"en_US","og_type":"article","og_title":"Perch\u00e9 il processo di Sales&Operations Planning?","og_description":"Sales Operations Planning \u2013 Scopri perch\u00e9 implementare un processo di Sales Operations Planning pu\u00f2 migliorare la pianificazione aziendale.","og_url":"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/digital-talk-why-companies-should-implement-salesoperations-planning-process\/","og_site_name":"Bonfiglioli Consulting","article_modified_time":"2025-11-13T06:19:13+00:00","og_image":[{"width":1024,"height":578,"url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/05\/ImmagineBANNER-SOP_GIUGNO2025-1024x578.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/digital-talk-perche-le-aziende-dovrebbero-implementare-il-processo-di-salesoperations-planning\/","url":"https:\/\/www.bonfiglioliconsulting.com\/events\/digital-talk-perche-le-aziende-dovrebbero-implementare-il-processo-di-salesoperations-planning\/","name":"Why the Sales&amp;Operations Planning process?","isPartOf":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/digital-talk-perche-le-aziende-dovrebbero-implementare-il-processo-di-salesoperations-planning\/#primaryimage"},"image":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/digital-talk-perche-le-aziende-dovrebbero-implementare-il-processo-di-salesoperations-planning\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/05\/ImmagineBANNER-SOP_GIUGNO2025.png","datePublished":"2023-05-22T11:31:15+00:00","dateModified":"2025-11-13T06:19:13+00:00","description":"Sales Operations Planning - Learn why implementing a Sales Operations Planning process can improve business planning.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bonfiglioliconsulting.com\/events\/digital-talk-perche-le-aziende-dovrebbero-implementare-il-processo-di-salesoperations-planning\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/digital-talk-perche-le-aziende-dovrebbero-implementare-il-processo-di-salesoperations-planning\/#primaryimage","url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/05\/ImmagineBANNER-SOP_GIUGNO2025.png","contentUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/05\/ImmagineBANNER-SOP_GIUGNO2025.png","width":1994,"height":1125,"caption":"In un ufficio ben illuminato, professionisti in abiti da lavoro esaminano un grafico. L'immagine presenta il testo: \"26 Giugno 2025 Digital Talk in Diretta Streaming\", che sottolinea l'importanza della pianificazione delle vendite e delle operazioni per le aziende che navigano nel panorama digitale in continua evoluzione."},{"@type":"WebSite","@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website","url":"https:\/\/www.bonfiglioliconsulting.com\/it\/","name":"Bonfiglioli Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonfiglioliconsulting.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"atf_populated":false,"_links":{"self":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/course\/44449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/types\/course"}],"version-history":[{"count":45,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/course\/44449\/revisions"}],"predecessor-version":[{"id":65269,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/course\/44449\/revisions\/65269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/media\/65268"}],"wp:attachment":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/media?parent=44449"}],"wp:term":[{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/tipologia?post=44449"},{"taxonomy":"content_type","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/content_type?post=44449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}