{"id":39075,"date":"2023-01-17T12:51:08","date_gmt":"2023-01-17T11:51:08","guid":{"rendered":"https:\/\/www.bcsoa.it\/?post_type=course&#038;p=39075"},"modified":"2025-11-20T15:20:19","modified_gmt":"2025-11-20T14:20:19","slug":"smed-method","status":"publish","type":"course","link":"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/metodo-smed\/","title":{"rendered":"\u201cSMED Method\u201d course: reduce Setup time for operational efficiency"},"content":{"rendered":"<div id=\"saz-block-block_ff716a1789a4300a34176b124688e793\" class=\"saz-block saz-block-acf-onda\" style=\"background-color: #ffffff\">\n    <div class=\"container-fluid\">\n                    <div class=\"row\">\n                <div class=\"col-lg-9 pl-0\">\n                    <svg id=\"onda-blocchi\" class=\"reverse\" data-name=\"onda\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 180\"><path class=\"cls-1\" d=\"M0,180H1000V.4S458.72-.5,279.85.4c-49,.25-68.29,7.31-161.7,105.9C94.46,131.3,49.5,174.7,0,180Z\" transform=\"translate(0 0)\" style=\"fill: #e3e9ed\"\/><\/svg>\n                <\/div>\n            <\/div>\n            <\/div>\n<\/div><div id=\"saz-block-id-FDMMui4bzS55\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-wAiMjIxvKaoQ\" class=\"saz-block saz-block-core-heading saz-block-backgroundcolor-light\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n<h2 class=\"wp-block-heading has-light-background-color has-background\"><strong>Learn about the full route<\/strong><\/h2>\n<\/div><\/div><\/div><\/div><div id=\"saz-block-id-9RWq0mrG2nmp\" class=\"saz-block saz-block\"><div class=\"container\"><div class=\"row\"><div class=\"col-12 col-lg-8 offset-lg-2\">\n\n<\/div><\/div><\/div><\/div><div id=\"saz-block-block_cb14d901272c7862ff515a17eeb08b89\" class=\"saz-block saz-block-acf-news-evidenza  py-4 py-lg-5\" style=\"background-color: #e3e9ed\">\n    <div class=\"container\">\n        <div class=\"row align-items-center\">\n\n            \n            <div class=\"col-lg-6 order-2\">\n                <img decoding=\"async\" class=\"img-fluid lazyload\" data-src=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2020\/03\/Banner-Lean-Expert-2024.jpg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1280px; --smush-placeholder-aspect-ratio: 1280\/720;\">\n            <\/div>\n            <div class=\"col-lg-5 order-lg-1 order-2 offset-lg-1\">\n                                    <div class=\"text-uppercase has-extrasmall-font-size mb-2 categoria-servizi  text-left\">\n                                                    <a class=\"text-gray pr-2\" href=\"https:\/\/www.bonfiglioliconsulting.com\/en\/typologies\/corsi-di-formazione\/percorsi-di-certificazione\/lean-excellence\/\">Lean Excellence<\/a>\n                                            <\/div>\n                                <h2 class=\"my-3 mt-lg-0\"><a class=\"text-gray\" href=\"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/lean-expert-certification-program\/\">Lean Expert | Certification Program<\/a><\/h2>\n\n                \n                                    <div class=\"mt-2 mb-3 has-small-font-size text-gray\">An 8-day course to learn about and try out the methods and tools of Lean Thinking and be able to choose and apply the most suitable tool using Lean Beginners.\nThe course includes the implementation and exposure of an improvement project in complete autonomy.<\/div>\n                                <a href=\"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/lean-expert-certification-program\/\" class=\"btn btn-secondary text-white\">Read more<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":null,"protected":false},"featured_media":58789,"menu_order":116,"template":"","tipologia":[98],"content_type":[154],"class_list":["post-39075","course","type-course","status-publish","has-post-thumbnail","hentry","tipologia-operational-excellence","content_type-corso"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corso Metodo SMED: Riduci i Tempi di Setup<\/title>\n<meta name=\"description\" content=\"Scopri come applicare lo SMED per ottimizzare i cambi formato, migliorare l&#039;efficienza produttiva e implementare il Visual Management.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/smed-method\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corso Metodo SMED: Riduci i Tempi di Setup\" \/>\n<meta property=\"og:description\" content=\"Scopri come applicare lo SMED per ottimizzare i cambi formato, migliorare l&#039;efficienza produttiva e implementare il Visual Management.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/smed-method\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonfiglioli Consulting\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-20T14:20:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/smed-2024-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/metodo-smed\\\/\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/metodo-smed\\\/\",\"name\":\"Corso Metodo SMED: Riduci i Tempi di Setup\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/metodo-smed\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/metodo-smed\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/smed-2024-scaled.jpg\",\"datePublished\":\"2023-01-17T11:51:08+00:00\",\"dateModified\":\"2025-11-20T14:20:19+00:00\",\"description\":\"Scopri come applicare lo SMED per ottimizzare i cambi formato, migliorare l'efficienza produttiva e implementare il Visual Management.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/metodo-smed\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/metodo-smed\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/smed-2024-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/smed-2024-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/\",\"name\":\"Bonfiglioli Consulting\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SMED Method Course: Reduce Setup Time","description":"Learn how to apply SMED to optimize changeovers, improve production efficiency and implement Visual Management.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/smed-method\/","og_locale":"en_US","og_type":"article","og_title":"Corso Metodo SMED: Riduci i Tempi di Setup","og_description":"Scopri come applicare lo SMED per ottimizzare i cambi formato, migliorare l'efficienza produttiva e implementare il Visual Management.","og_url":"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/smed-method\/","og_site_name":"Bonfiglioli Consulting","article_modified_time":"2025-11-20T14:20:19+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/smed-2024-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/metodo-smed\/","url":"https:\/\/www.bonfiglioliconsulting.com\/events\/metodo-smed\/","name":"SMED Method Course: Reduce Setup Time","isPartOf":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/metodo-smed\/#primaryimage"},"image":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/metodo-smed\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/smed-2024-scaled.jpg","datePublished":"2023-01-17T11:51:08+00:00","dateModified":"2025-11-20T14:20:19+00:00","description":"Learn how to apply SMED to optimize changeovers, improve production efficiency and implement Visual Management.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bonfiglioliconsulting.com\/events\/metodo-smed\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/metodo-smed\/#primaryimage","url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/smed-2024-scaled.jpg","contentUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/smed-2024-scaled.jpg","width":2560,"height":1440},{"@type":"WebSite","@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website","url":"https:\/\/www.bonfiglioliconsulting.com\/it\/","name":"Bonfiglioli Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonfiglioliconsulting.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"atf_populated":false,"_links":{"self":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/course\/39075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/types\/course"}],"version-history":[{"count":28,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/course\/39075\/revisions"}],"predecessor-version":[{"id":70436,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/course\/39075\/revisions\/70436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/media\/58789"}],"wp:attachment":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/media?parent=39075"}],"wp:term":[{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/tipologia?post=39075"},{"taxonomy":"content_type","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/content_type?post=39075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}