{"id":38877,"date":"2023-01-13T13:34:14","date_gmt":"2023-01-13T12:34:14","guid":{"rendered":"https:\/\/www.bcsoa.it\/?post_type=course&#038;p=38877"},"modified":"2025-11-13T07:20:40","modified_gmt":"2025-11-13T06:20:40","slug":"digital-talk-delpharm-implementation-lean-six-sigma","status":"publish","type":"course","link":"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/digital-talk-delpharm-implementazione-lean-six-sigma\/","title":{"rendered":"Digital Talk | Delpharm's experience: a path to implementing Lean Six Sigma from training to project management in production"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":null,"protected":false},"featured_media":38878,"menu_order":30901,"template":"","tipologia":[50],"content_type":[155],"class_list":["post-38877","course","type-course","status-publish","has-post-thumbnail","hentry","tipologia-workshop-digital-talk","content_type-evento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dalla formazione alla gestione di progetti in produzione<\/title>\n<meta name=\"description\" content=\"Esperienza Delpharm: implementazione Lean Six Sigma dalla formazione alla gestione dei progetti produttivi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/digital-talk-delpharm-implementation-lean-six-sigma\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dalla formazione alla gestione di progetti in produzione\" \/>\n<meta property=\"og:description\" content=\"Esperienza Delpharm: implementazione Lean Six Sigma dalla formazione alla gestione dei progetti produttivi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/digital-talk-delpharm-implementation-lean-six-sigma\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonfiglioli Consulting\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T06:20:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/BANNER-DELPHARM.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1411\" \/>\n\t<meta property=\"og:image:height\" content=\"799\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/digital-talk-delpharm-implementazione-lean-six-sigma\\\/\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/digital-talk-delpharm-implementazione-lean-six-sigma\\\/\",\"name\":\"Dalla formazione alla gestione di progetti in produzione\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/digital-talk-delpharm-implementazione-lean-six-sigma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/digital-talk-delpharm-implementazione-lean-six-sigma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/BANNER-DELPHARM.jpg\",\"datePublished\":\"2023-01-13T12:34:14+00:00\",\"dateModified\":\"2025-11-13T06:20:40+00:00\",\"description\":\"Esperienza Delpharm: implementazione Lean Six Sigma dalla formazione alla gestione dei progetti produttivi.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/digital-talk-delpharm-implementazione-lean-six-sigma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/events\\\/digital-talk-delpharm-implementazione-lean-six-sigma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/BANNER-DELPHARM.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/BANNER-DELPHARM.jpg\",\"width\":1411,\"height\":799},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/\",\"name\":\"Bonfiglioli Consulting\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bonfiglioliconsulting.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"From training to project management in production","description":"Delpharm experience: Lean Six Sigma implementation from training to production project management.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/digital-talk-delpharm-implementation-lean-six-sigma\/","og_locale":"en_US","og_type":"article","og_title":"Dalla formazione alla gestione di progetti in produzione","og_description":"Esperienza Delpharm: implementazione Lean Six Sigma dalla formazione alla gestione dei progetti produttivi.","og_url":"https:\/\/www.bonfiglioliconsulting.com\/en\/events\/digital-talk-delpharm-implementation-lean-six-sigma\/","og_site_name":"Bonfiglioli Consulting","article_modified_time":"2025-11-13T06:20:40+00:00","og_image":[{"width":1411,"height":799,"url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/BANNER-DELPHARM.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/digital-talk-delpharm-implementazione-lean-six-sigma\/","url":"https:\/\/www.bonfiglioliconsulting.com\/events\/digital-talk-delpharm-implementazione-lean-six-sigma\/","name":"From training to project management in production","isPartOf":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/digital-talk-delpharm-implementazione-lean-six-sigma\/#primaryimage"},"image":{"@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/digital-talk-delpharm-implementazione-lean-six-sigma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/BANNER-DELPHARM.jpg","datePublished":"2023-01-13T12:34:14+00:00","dateModified":"2025-11-13T06:20:40+00:00","description":"Delpharm experience: Lean Six Sigma implementation from training to production project management.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bonfiglioliconsulting.com\/events\/digital-talk-delpharm-implementazione-lean-six-sigma\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bonfiglioliconsulting.com\/events\/digital-talk-delpharm-implementazione-lean-six-sigma\/#primaryimage","url":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/BANNER-DELPHARM.jpg","contentUrl":"https:\/\/www.bonfiglioliconsulting.com\/wp-content\/uploads\/2023\/01\/BANNER-DELPHARM.jpg","width":1411,"height":799},{"@type":"WebSite","@id":"https:\/\/www.bonfiglioliconsulting.com\/it\/#website","url":"https:\/\/www.bonfiglioliconsulting.com\/it\/","name":"Bonfiglioli Consulting","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bonfiglioliconsulting.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"atf_populated":false,"_links":{"self":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/course\/38877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/types\/course"}],"version-history":[{"count":19,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/course\/38877\/revisions"}],"predecessor-version":[{"id":40875,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/course\/38877\/revisions\/40875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/media\/38878"}],"wp:attachment":[{"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/media?parent=38877"}],"wp:term":[{"taxonomy":"tipologia","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/tipologia?post=38877"},{"taxonomy":"content_type","embeddable":true,"href":"https:\/\/www.bonfiglioliconsulting.com\/en\/wp-json\/wp\/v2\/content_type?post=38877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}